{"id":208397,"date":"2023-06-01T12:22:10","date_gmt":"2023-06-01T15:22:10","guid":{"rendered":"https:\/\/www.trustedtranslations.com\/?post_type=blog&#038;p=208397"},"modified":"2023-06-01T12:22:10","modified_gmt":"2023-06-01T15:22:10","slug":"eine-stadt-fuenf-offizielle-sprachen","status":"publish","type":"blog","link":"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen","title":{"rendered":"Eine Stadt, f\u00fcnf offizielle Sprachen"},"content":{"rendered":"<p>Tief im Herzen des amazonischen Regenwaldes errichtet eine riesige Gemeinde (etwa die Gr\u00f6\u00dfe Tennessees) ein einzigartiges linguistisches Erbe: sie hat f\u00fcnf offizielle Sprachen!<\/p>\n<p>An Venezuela und Kolumbien angrenzend hat S\u00e3o Gabriel da Cachoeira eine Bev\u00f6lkerung von unter 50.000. Etwa 80% ihrer Einwohner sind indigen, wobei 23 der \u00fcber 300 brasilianischen Ethnien in dieser Gemeinde ans\u00e4ssig sind.<\/p>\n<h2><strong>Eine Stadt, viele Ethnien<\/strong><\/h2>\n<p>Neben dem offiziellen <a href=\"https:\/\/www.trustedtranslations.com\/de\/sprache\/portugiesisch\">Portugiesisch<\/a> in Brasilien hat die Gemeinde von S\u00e3o Gabriel da Cachoeira seit 2002 die Sprachen Nheengatu, Baniwa und Tukano als ko-offizielle Sprachen anerkannt. Alle werden in 750 nahegelegenen Gemeinschaften gesprochen, zusammen mit Yanomamo, welche im Jahr 2017 in die offizielle Liste aufgenommen wurde.<\/p>\n<p>Auch wenn sie f\u00fcr die Au\u00dfenwelt weitgehend unbekannt ist, ist ihre Reichweite international:<\/p>\n<ul>\n<li><strong>Nheengatu <\/strong>(14.000 Sprecher) ist ein Tupi-Dialekt, der von den kolonisierenden Jesuiten als <em>Verkehrssprache<\/em> zur Kommunikation mit indigenen Menschen in ganz Amazonien eingesetzt wurde.<\/li>\n<li><strong>Baniwa<\/strong> (6.000 Sprecher) ist ein arawakanischer Dialekt, der eng mit dem <a href=\"http:\/\/www.native-languages.org\/curripaco.htm\" target=\"_blank\" rel=\"noopener\">Curripaco<\/a> und <a href=\"http:\/\/www.native-languages.org\/carutana.htm\" target=\"_blank\" rel=\"noopener\">Carutana<\/a> verwandt ist und die Gemeinden in Brasilien, Venezuela und Kolumbien miteinander verbindet.<\/li>\n<li><strong>Tukano<\/strong> (4.600 Sprecher) ist ein <a href=\"https:\/\/www.trustedtranslations.com\/de\/blog\/was-ist-ein-sprachisolat\">Isolat<\/a>, das in zwei Regionen in Westamazonien gesprochen wird und Brasilien, Kolumbien, Ecuador und Peru umfasst.<\/li>\n<li><strong>Yanomamo <\/strong>(20,000 Sprecher) ist ein Sprachisolat, das von gr\u00f6\u00dftenteils einsprachen Yanomami-Gemeinschaften entlang des Amazonas-Flusses in Nordbrasilien und dem Orinoco-Fluss in S\u00fcdvenezuela gesprochen wird.<\/li>\n<\/ul>\n<p><strong>Hinweis:<\/strong> Die gesch\u00e4tzte Anzahl der Sprecher k\u00f6nnte sich w\u00e4hrend der COVID-19-Pandemie reduziert haben, da keine aktualisierten Statistiken verf\u00fcgbar sind.<\/p>\n<h2><strong>Echos aus Europa<\/strong><\/h2>\n<p>Diese breit angelegte Gesetzgebung sch\u00fctzt auch ein paar beinahe ausgestorbene europ\u00e4ische Sprachen. Im S\u00fcden Brasiliens wurden neun europ\u00e4ische Sprachen in Gemeinden offiziell gemacht, die von europ\u00e4ischen Einwanderern heimgesucht wurden, insbesondere im sp\u00e4ten 19. und fr\u00fchen 20. Jahrhundert.<\/p>\n<p>Mit Jahrzehnten von Armut und Verfolgung, die mit den Weltkriegen den H\u00f6hepunkt erreicht hatten, \u00fcberquerten die Einwandererwellen ununterbrochen den Atlantik, um in der neuen Welt ein besseres Leben zu finden. Viele haben sich angepasst und sind mit der Mainstream-Gesellschaft verschmolzen, w\u00e4hrend es andere bevorzugten, sich an ihre alten Br\u00e4uche (und Sprachen) in Enklaven zu klammern.<\/p>\n<p>Einige dieser Sprachen\u2014wie das Pomoranische (Deutschland und Polen), Talian (ein venezianischer Dialekt) und Hunsr\u00fcckisch (ein deutscher Dialekt, der nur in S\u00fcdbrasilien, Argentinien und Paraguay gesprochen wird)\u2014sind aktuell in Europa ausgestorben.<\/p>\n<h2><strong>Sprache als Waffe f\u00fcr soziale Gerechtigkeit<\/strong><\/h2>\n<p>Trotz der begrenzten Finanzierung und politischen Unterst\u00fctzung wendet sich das Blatt. Es gibt Anzeichen f\u00fcr bessere Zeiten f\u00fcr die indigenen Gemeinschaften von Brasilien und ihren Sprachen.<\/p>\n<p>Einer dieser Vorboten ist das neue brasilianische Ministerium f\u00fcr indigene Menschen, geleitet von der Ministerin S\u00f4nia Sousa Silva Santos, die sich mit ihren Stammeswurzeln identifiziert: Sonia Guajajara. Sie wurde im <a href=\"https:\/\/time.com\/collection\/100-most-influential-people-2022\/6177858\/sonia-guajajara\/\" target=\"_blank\" rel=\"noopener\">Time-Magazin<\/a> als eine der 100 einflussreichsten Personen im Jahr 2022 aufgelistet.<\/p>\n<h2><strong>Politik vs. Menschen <\/strong><\/h2>\n<p>Wahrscheinlich von der reichen brasilianischen Flickwerk-Geschichte angespornt, hat dieses innovative Konzept der Gesetzgebung bez\u00fcglich Sprachen auf Gemeindeebene die Absicht, kulturelle Identit\u00e4ten spezifischer Gemeinschaften zu besch\u00fctzen. Es soll auch die gesellschaftliche Mobilit\u00e4t f\u00f6rdern und Minderheitensprachen sch\u00fctzen.<\/p>\n<p>Diese <a href=\"https:\/\/www.trustedtranslations.com\/de\/blog\/internationales-jahrzehnt-der-indigenen-sprachen\">indigenen Sprachen<\/a> werden besser sichtbar, weil Schulen jetzt dazu verpflichtet sind, mindestens eine davon zu schulen. Lokale Notare ben\u00f6tigen ebenfalls zweisprachige Angestellte, um Stammesmitglieder zu unterst\u00fctzen, die ihre Registrierungsdienstleistungen ben\u00f6tigen. Dies wird durch eine Aufsichtskommission f\u00fcr indigene Rechte sichergestellt, die von den amazonischen Landgerichten gegr\u00fcndet wurde.<\/p>\n<p>Den Zugriff auf die Dokumentation und die Standes\u00e4mter sicherzustellen, ist unerl\u00e4sslich f\u00fcr indigene Gemeinschaften in Amazonien. Die Eigent\u00fcmerschaft von gro\u00dfen Teilen des Landes (und seinen reichen Bodensch\u00e4tzen) wird oft hei\u00df diskutiert, mit t\u00f6dlichen Ergebnissen sogar f\u00fcr unschuldige Zuschauer\u2014darunter der Indigenenexperte Bruno Pereira und der Journalist Dom Philips.<\/p>\n<h2>\u00a0<strong>Pfeile gegen AK47 <\/strong><\/h2>\n<p>Die Agrarwirtschaft ist ein skrupelloser m\u00e4chtiger Akteur in dieser Region und generiert beinahe ein Vierteil des brasilianischen Bruttoinlandsproduktes, mit \u00fcber f\u00fcnfzig Millionen Rindern in Amazonien. Ein weiterer verachtenswerter Akteur in der Region ist der illegale Bergbau, welcher Fl\u00fcsse mit Quecksilber durch Goldw\u00e4scherei verschmutzt, w\u00e4hrend die Abholzung uralte B\u00e4ume f\u00e4llt, um Weidel\u00e4nder zu schaffen, und illegale Br\u00e4nde f\u00fcr riesige Monokultur-Plantagen Platz machen.<\/p>\n<p>Darum ist es so wichtig f\u00fcr Institutionen auf allen Ebenen, Dienstleistungen f\u00fcr lokale Gemeinschaften in ihren eigenen Dialekten bereitzustellen. Ihre Sprachen sind das Grundger\u00fcst f\u00fcr diese <a href=\"https:\/\/www.trustedtranslations.com\/de\/blog\/klimakrise-und-sprachverlust\">bedrohten Gemeinschaften<\/a> (oft mit beschr\u00e4nktem Portugiesisch), welche wiederum die Besch\u00fctzer Ihrer Heimat, dem Regenwald, sind.<\/p>\n<h2><strong>Die Besch\u00fctzer besch\u00fctzen <\/strong><\/h2>\n<p>\u00dcber zehn Millionen Jahre alt und einmal Heim f\u00fcr 390 Milliarden B\u00e4ume ist dieses gewaltige Flussgebiet ein un\u00fcbertroffener Zufluchtsort f\u00fcr die Biodiversit\u00e4t in einem gro\u00dfen Bereich von S\u00fcdamerika. Alle diese negativen Faktoren dr\u00e4ngen den Amazonas-Regenwald jedoch zu einen Punkt, an dem es kein Zur\u00fcck mehr gibt: der Kipppunkt f\u00fcr die globale Erderw\u00e4rmung.<\/p>\n<p>Auch wenn nicht direkt daran beteiligt, indigene Kulturen zu sch\u00fctzen, ist sich <em><em>Trusted Translations<\/em><\/em> der Wichtigkeit dieser alten Sprachen deutlich bewusst. Sein hoch qualifiziertes Personal arbeitet allt\u00e4glich mit innovativen Tools (wie <a href=\"https:\/\/www.trustedtranslations.com\/de\/dienstleistungen\/menschlich\/lokalisierung\">Lokalisierung<\/a>), die Internetbenutzer dazu anzuspornen, ihre nativen Sprachen zu w\u00e4hlen, anstatt sich online automatisch f\u00fcr Portugiesisch zu entscheiden. Denn dieses unbezahlbare sprachliche Erbe zu vergessen w\u00fcrde ein irreparabler Verlust f\u00fcr die gesamte Welt bedeuten.<\/p>\n<p>Bild von\u00a0Hans Schwarzkopf\u00a0von\u00a0Pixabay<\/p>\n","protected":false},"excerpt":{"rendered":"Tief im Herzen des amazonischen Regenwaldes errichtet eine riesige Gemeinde (etwa die Gr\u00f6\u00dfe Tennessees) ein einzigartiges linguistisches Erbe: sie hat f\u00fcnf offizielle Sprachen! An Venezuela und Kolumbien angrenzend hat S\u00e3o\u2026\n","protected":false},"author":115,"featured_media":206448,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[17433],"tags":[18995,12585,18998,18994,18735,18721],"class_list":["post-208397","blog","type-blog","status-publish","format-standard","has-post-thumbnail","hentry","category-languages-de","tag-amazonas-es","tag-indigenous-languages","tag-langues-minoritaires-fr","tag-minderheitensprachen","tag-portugiesischen-sprache","tag-portuguese-language"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eine Stadt, f\u00fcnf offizielle Sprachen - Trusted Translations, Inc.<\/title>\n<meta name=\"description\" content=\"Tief im amazonischen Regenwald errichtet eine gro\u00dfe Gemeinde ein einzigartiges linguistisches Erbe: sie hat f\u00fcnf offizielle Sprachen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eine Stadt, f\u00fcnf offizielle Sprachen - Trusted Translations, Inc.\" \/>\n<meta property=\"og:description\" content=\"Tief im amazonischen Regenwald errichtet eine gro\u00dfe Gemeinde ein einzigartiges linguistisches Erbe: sie hat f\u00fcnf offizielle Sprachen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen\" \/>\n<meta property=\"og:site_name\" content=\"Trusted Translations, Inc.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Trusted.Translations\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2023\/05\/amazon-indians-ga97e8e9f3_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TrustedT9ns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/blog\\\/eine-stadt-fuenf-offizielle-sprachen#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/blog\\\/eine-stadt-fuenf-offizielle-sprachen\"},\"author\":{\"name\":\"Rafael Dos Santos\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/#\\\/schema\\\/person\\\/dd8c03f4a3b77ace16658b5e0bf11828\"},\"headline\":\"Eine Stadt, f\u00fcnf offizielle Sprachen\",\"datePublished\":\"2023-06-01T15:22:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/blog\\\/eine-stadt-fuenf-offizielle-sprachen\"},\"wordCount\":872,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/blog\\\/eine-stadt-fuenf-offizielle-sprachen#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/amazon-indians-ga97e8e9f3_1920.jpg\",\"keywords\":[\"Amazonas\",\"indigenous languages\",\"langues minoritaires\",\"Minderheitensprachen\",\"Portugiesischen Sprache\",\"Portuguese language\"],\"articleSection\":[\"Sprachen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/blog\\\/eine-stadt-fuenf-offizielle-sprachen\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/blog\\\/eine-stadt-fuenf-offizielle-sprachen\",\"name\":\"Eine Stadt, f\u00fcnf offizielle Sprachen - Trusted Translations, Inc.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/blog\\\/eine-stadt-fuenf-offizielle-sprachen#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/blog\\\/eine-stadt-fuenf-offizielle-sprachen#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/amazon-indians-ga97e8e9f3_1920.jpg\",\"description\":\"Tief im amazonischen Regenwald errichtet eine gro\u00dfe Gemeinde ein einzigartiges linguistisches Erbe: sie hat f\u00fcnf offizielle Sprachen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/blog\\\/eine-stadt-fuenf-offizielle-sprachen#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/blog\\\/eine-stadt-fuenf-offizielle-sprachen\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/blog\\\/eine-stadt-fuenf-offizielle-sprachen#primaryimage\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/amazon-indians-ga97e8e9f3_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/amazon-indians-ga97e8e9f3_1920.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"amazon indians ga97e8e9f3 1920\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/blog\\\/eine-stadt-fuenf-offizielle-sprachen#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/blog\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sprachen\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/blog\\\/topics\\\/languages-de\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Eine Stadt, f\u00fcnf offizielle Sprachen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/\",\"name\":\"Trusted Translations, Inc.\",\"description\":\"Leader in translation and interpretation services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/#organization\"},\"alternateName\":\"Trusted Translations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/#organization\",\"name\":\"Trusted Translations\",\"alternateName\":\"Trusted Translations, Inc.\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"contentUrl\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"width\":500,\"height\":196,\"caption\":\"Trusted Translations\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Trusted.Translations\",\"https:\\\/\\\/x.com\\\/TrustedT9ns\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/trusted-translations\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/#\\\/schema\\\/person\\\/dd8c03f4a3b77ace16658b5e0bf11828\",\"name\":\"Rafael Dos Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/26331e7a694d2e04a19be311cb2030dd84efd4746ad6690ce40e02b02cf8ec6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/26331e7a694d2e04a19be311cb2030dd84efd4746ad6690ce40e02b02cf8ec6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/26331e7a694d2e04a19be311cb2030dd84efd4746ad6690ce40e02b02cf8ec6b?s=96&d=mm&r=g\",\"caption\":\"Rafael Dos Santos\"},\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/de\\\/author\\\/rafaelds\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eine Stadt, f\u00fcnf offizielle Sprachen - Trusted Translations, Inc.","description":"Tief im amazonischen Regenwald errichtet eine gro\u00dfe Gemeinde ein einzigartiges linguistisches Erbe: sie hat f\u00fcnf offizielle Sprachen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen","og_locale":"de_DE","og_type":"article","og_title":"Eine Stadt, f\u00fcnf offizielle Sprachen - Trusted Translations, Inc.","og_description":"Tief im amazonischen Regenwald errichtet eine gro\u00dfe Gemeinde ein einzigartiges linguistisches Erbe: sie hat f\u00fcnf offizielle Sprachen.","og_url":"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen","og_site_name":"Trusted Translations, Inc.","article_publisher":"https:\/\/www.facebook.com\/Trusted.Translations","og_image":[{"width":1920,"height":1280,"url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2023\/05\/amazon-indians-ga97e8e9f3_1920.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TrustedT9ns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen#article","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen"},"author":{"name":"Rafael Dos Santos","@id":"https:\/\/www.trustedtranslations.com\/de\/#\/schema\/person\/dd8c03f4a3b77ace16658b5e0bf11828"},"headline":"Eine Stadt, f\u00fcnf offizielle Sprachen","datePublished":"2023-06-01T15:22:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen"},"wordCount":872,"publisher":{"@id":"https:\/\/www.trustedtranslations.com\/de\/#organization"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen#primaryimage"},"thumbnailUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2023\/05\/amazon-indians-ga97e8e9f3_1920.jpg","keywords":["Amazonas","indigenous languages","langues minoritaires","Minderheitensprachen","Portugiesischen Sprache","Portuguese language"],"articleSection":["Sprachen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen","url":"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen","name":"Eine Stadt, f\u00fcnf offizielle Sprachen - Trusted Translations, Inc.","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen#primaryimage"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen#primaryimage"},"thumbnailUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2023\/05\/amazon-indians-ga97e8e9f3_1920.jpg","description":"Tief im amazonischen Regenwald errichtet eine gro\u00dfe Gemeinde ein einzigartiges linguistisches Erbe: sie hat f\u00fcnf offizielle Sprachen.","breadcrumb":{"@id":"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen#primaryimage","url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2023\/05\/amazon-indians-ga97e8e9f3_1920.jpg","contentUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2023\/05\/amazon-indians-ga97e8e9f3_1920.jpg","width":1920,"height":1280,"caption":"amazon indians ga97e8e9f3 1920"},{"@type":"BreadcrumbList","@id":"https:\/\/www.trustedtranslations.com\/de\/blog\/eine-stadt-fuenf-offizielle-sprachen#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trustedtranslations.com\/de"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.trustedtranslations.com\/de\/blog"},{"@type":"ListItem","position":3,"name":"Sprachen","item":"https:\/\/www.trustedtranslations.com\/de\/blog\/topics\/languages-de"},{"@type":"ListItem","position":4,"name":"Eine Stadt, f\u00fcnf offizielle Sprachen"}]},{"@type":"WebSite","@id":"https:\/\/www.trustedtranslations.com\/de\/#website","url":"https:\/\/www.trustedtranslations.com\/de\/","name":"Trusted Translations, Inc.","description":"Leader in translation and interpretation services.","publisher":{"@id":"https:\/\/www.trustedtranslations.com\/de\/#organization"},"alternateName":"Trusted Translations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trustedtranslations.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.trustedtranslations.com\/de\/#organization","name":"Trusted Translations","alternateName":"Trusted Translations, Inc.","url":"https:\/\/www.trustedtranslations.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.trustedtranslations.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","contentUrl":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","width":500,"height":196,"caption":"Trusted Translations"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Trusted.Translations","https:\/\/x.com\/TrustedT9ns","https:\/\/www.linkedin.com\/company\/trusted-translations"]},{"@type":"Person","@id":"https:\/\/www.trustedtranslations.com\/de\/#\/schema\/person\/dd8c03f4a3b77ace16658b5e0bf11828","name":"Rafael Dos Santos","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/26331e7a694d2e04a19be311cb2030dd84efd4746ad6690ce40e02b02cf8ec6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/26331e7a694d2e04a19be311cb2030dd84efd4746ad6690ce40e02b02cf8ec6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/26331e7a694d2e04a19be311cb2030dd84efd4746ad6690ce40e02b02cf8ec6b?s=96&d=mm&r=g","caption":"Rafael Dos Santos"},"url":"https:\/\/www.trustedtranslations.com\/de\/author\/rafaelds"}]}},"toolset-meta":{"cpt-for-blogs":{"revisor":{"type":"textfield","raw":""},"revisor-image":{"type":"image","raw":"","attachment_id":null},"revisor-description":{"type":"textfield","raw":""},"revisor-link":{"type":"url","raw":""}}},"_links":{"self":[{"href":"https:\/\/www.trustedtranslations.com\/de\/wp-json\/wp\/v2\/blog\/208397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trustedtranslations.com\/de\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.trustedtranslations.com\/de\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/de\/wp-json\/wp\/v2\/users\/115"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/de\/wp-json\/wp\/v2\/comments?post=208397"}],"version-history":[{"count":0,"href":"https:\/\/www.trustedtranslations.com\/de\/wp-json\/wp\/v2\/blog\/208397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/de\/wp-json\/wp\/v2\/media\/206448"}],"wp:attachment":[{"href":"https:\/\/www.trustedtranslations.com\/de\/wp-json\/wp\/v2\/media?parent=208397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/de\/wp-json\/wp\/v2\/categories?post=208397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/de\/wp-json\/wp\/v2\/tags?post=208397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}