{"id":113522,"date":"2018-11-03T13:52:44","date_gmt":"2018-11-03T13:52:44","guid":{"rendered":"https:\/\/www.trustedtranslations.com\/?p=113522"},"modified":"2023-01-26T12:48:18","modified_gmt":"2023-01-26T15:48:18","slug":"mt-de-babel-a-metropolis","status":"publish","type":"blog","link":"https:\/\/www.trustedtranslations.com\/es\/blog\/mt-de-babel-a-metropolis","title":{"rendered":"MT: De Babel a Metr\u00f3polis"},"content":{"rendered":"<p>Como una reflexi\u00f3n acerca de una de las primeras exploraciones cinematogr\u00e1ficas sobre la relaci\u00f3n entre tecnolog\u00eda y humanidad, la pel\u00edcula Metr\u00f3polis (considerada como una de las primeras del g\u00e9nero ciencia ficci\u00f3n jam\u00e1s creadas) reflexion\u00f3 sobre el delicado equilibrio entre el hombre y la m\u00e1quina trabajando juntos para lograr el progreso.<\/p>\n<p>Metr\u00f3polis, estrenada originalmente en 1927 y dirigida por el alem\u00e1n Fritz Lang, cuenta la historia de una ciudad futurista llena de rascacielos de ensue\u00f1o y carreteras construidas exclusivamente para la comodidad de la alta sociedad. Sin embargo, la ciudad subterr\u00e1nea de trabajadores tiene una historia muy diferente que contar. Atrapados en un mundo subterr\u00e1neo proletario de torturas mec\u00e1nicas, los esclavos de la clase trabajadora se alejan, d\u00eda tras d\u00eda, alienados, dentro de los vientres de m\u00e1quinas demon\u00edacas que mantienen a la ciudad en lo alto sin problemas para las clases altas. Sin descansos ni un gramo de compasi\u00f3n, los trabajadores se esfuerzan por hacer turnos de 10 horas a la vez hasta que colapsan por el agotamiento y son reemplazados por la pr\u00f3xima ola de abejas obreras con el cerebro adormecido.<\/p>\n<p>El conflicto dentro de la historia no es dif\u00edcil de imaginar: el levantamiento es inminente y amenaza la totalidad del sistema social e incluso infraestructural de la ciudad.<\/p>\n<p><em>\u00abNo puede haber comprensi\u00f3n entre las manos y el cerebro a menos que el coraz\u00f3n act\u00fae como mediador\u00bb.<\/em><\/p>\n<p>Esta fue la moraleja b\u00e1sica de la historia de Lang. Los trabajadores representaron las manos, tirando incansablemente de las palancas y girando las perillas para que el resto de la sociedad civilizada pueda cumplir con sus propios est\u00e1ndares m\u00e1s altos, manteniendo ese poder en sus propias manos, pero incapaz de realizarlo por completo. Jon Fredersen, el creador y gobernante de la ciudad, representa el cerebro: fr\u00edvolo y completamente racional en su visi\u00f3n de la explotaci\u00f3n de la clase baja. Si es eficiente, cumple con su prop\u00f3sito tecnol\u00f3gico. Pero \u00bfa qu\u00e9 precio? \u00bfQu\u00e9 peligros conlleva?<\/p>\n<p>Solo su hijo Freder, que est\u00e1 expuesto a los horrores de la vida en el inframundo cuando un d\u00eda se escabulle en busca de Mar\u00eda (la mujer de la que se enamora), es capaz de sentir compasi\u00f3n por sus hermanos y hermanas subterr\u00e1neos. Y es \u00e9l qui\u00e9n luchar\u00e1 para que ambas partes se unan en un acuerdo civilizado al desempe\u00f1ar el papel de mediador (el coraz\u00f3n que conecta las manos y el cerebro).<\/p>\n<p>El mito b\u00e1sico sobre el que se erige Metr\u00f3polis es el relato b\u00edblico de la Torre de Babel, en el que los hombres se esforzaron por alcanzar la divinidad a trav\u00e9s del progreso, tratando de construir la torre m\u00e1s alta que existe para alcanzar el reino de los cielos. Un proyecto tan ambicioso y divino que terminar\u00eda colapsando sobre ellos.<\/p>\n<p>Entonces, \u00bfqu\u00e9 debemos hacer con esto y qu\u00e9 tiene que ver todo esto con el crecimiento creciente de la tecnolog\u00eda de Traducci\u00f3n Autom\u00e1tica (o <em>machine translation, MT<\/em>) en la industria de la traducci\u00f3n?<\/p>\n<p>En primer lugar, el lenguaje en s\u00ed tuvo un papel importante en el derrumbamiento de la Torre de Babel. Al parecer, Dios se sinti\u00f3 ofendido por la audacia de la humanidad al tratar de superarse esforz\u00e1ndose por alcanzar la divinidad. As\u00ed, a modo de castigo por su vanidad, el Se\u00f1or confundi\u00f3 sus idiomas para que ninguno de ellos pudiera comunicarse, desatando tal caos y confusi\u00f3n sobre la ciudad que la torre misma y el proyecto completo se derrumbaron bajo sus pies como consecuencia directa de su ira divina. Los trabajadores, a\u00fan incapaces de comunicarse entre s\u00ed, se expandieron luego por la tierra, fundando sus propias culturas y civilizaciones. Esto explicar\u00eda nuestra diversidad cultural y ling\u00fc\u00edstica global. Babel fue el principio, pero tambi\u00e9n podr\u00eda haber sido el final.<\/p>\n<p>A medida que los humanos luchamos por la perfecci\u00f3n a trav\u00e9s de la tecnolog\u00eda, a veces nos perdemos en el frenes\u00ed de jugar a Dios. \u00bfPor qu\u00e9 no es la Traducci\u00f3n Autom\u00e1tica (o la Inteligencia Artificial) una simulaci\u00f3n simplificada de la inteligencia humana en acci\u00f3n? \u00bfNo nos estaremos esforzando en recrear un ser sensible, una especie de aut\u00f3mata, que podr\u00eda pensar como un ling\u00fcista viviente mientras puede procesar informaci\u00f3n en unos pocos segundos? \u00bfUn ser o artilugio humanizado que podr\u00eda trabajar durante horas y horas sin ning\u00fan tipo de nutrici\u00f3n o salario? Eso me suena muy parecido a Metr\u00f3polis.<\/p>\n<p>Entonces, \u00bfestamos reeditando el mito de la Torre de Babel a prop\u00f3sito? \u00bfNo nos ha ense\u00f1ado nada la historia de Lang (o la de la Biblia)?<\/p>\n<p>Incluso si esos d\u00edas a\u00fan parecen lejanos en el futuro, todav\u00eda estamos viviendo al borde.\u00a0Porque ya somos los mediadores de hoy, abriendo el camino entre los ling\u00fcistas que trabajan duro y los ni\u00f1os mimados del jard\u00edn del Ed\u00e9n.<\/p>\n<p>Al menos por ahora, debemos ser el coraz\u00f3n entre las manos y el cerebro.<\/p>\n","protected":false},"excerpt":{"rendered":"Como una reflexi\u00f3n acerca de una de las primeras exploraciones cinematogr\u00e1ficas sobre la relaci\u00f3n entre tecnolog\u00eda y humanidad, la pel\u00edcula Metr\u00f3polis (considerada como una de las primeras del g\u00e9nero ciencia\u2026\n","protected":false},"author":72,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8893],"tags":[],"class_list":["post-113522","blog","type-blog","status-publish","format-standard","hentry","category-para-traductores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MT: De Babel a Metr\u00f3polis - Trusted Translations<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/mt-de-babel-a-metropolis\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MT: De Babel a Metr\u00f3polis - Trusted Translations\" \/>\n<meta property=\"og:description\" content=\"Como una reflexi\u00f3n acerca de una de las primeras exploraciones cinematogr\u00e1ficas sobre la relaci\u00f3n entre tecnolog\u00eda y humanidad, la pel\u00edcula Metr\u00f3polis (considerada como una de las primeras del g\u00e9nero ciencia...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trustedtranslations.com\/es\/blog\/mt-de-babel-a-metropolis\" \/>\n<meta property=\"og:site_name\" content=\"Trusted Translations\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Trusted.Translations\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-26T15:48:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/06\/tt-logo-2-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"216\" \/>\n\t<meta property=\"og:image:height\" content=\"94\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TrustedT9ns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/mt-de-babel-a-metropolis#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/mt-de-babel-a-metropolis\"},\"author\":{\"name\":\"patriciot\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/1fc8d0c2afab85b7c11a12900981da82\"},\"headline\":\"MT: De Babel a Metr\u00f3polis\",\"datePublished\":\"2018-11-03T13:52:44+00:00\",\"dateModified\":\"2023-01-26T15:48:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/mt-de-babel-a-metropolis\"},\"wordCount\":880,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"articleSection\":[\"Para Traductores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/mt-de-babel-a-metropolis#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/mt-de-babel-a-metropolis\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/mt-de-babel-a-metropolis\",\"name\":\"MT: De Babel a Metr\u00f3polis - Trusted Translations\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/mt-de-babel-a-metropolis#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/mt-de-babel-a-metropolis\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/mt-de-babel-a-metropolis#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Para Traductores\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/categorias\\\/para-traductores\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"MT: De Babel a Metr\u00f3polis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"name\":\"Trusted Translations, Inc.\",\"description\":\"Leader in translation and interpretation services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"alternateName\":\"Trusted Translations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\",\"name\":\"Trusted Translations\",\"alternateName\":\"Trusted Translations, Inc.\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"contentUrl\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"width\":500,\"height\":196,\"caption\":\"Trusted Translations\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Trusted.Translations\",\"https:\\\/\\\/x.com\\\/TrustedT9ns\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/trusted-translations\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/1fc8d0c2afab85b7c11a12900981da82\",\"name\":\"patriciot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"patriciot\"},\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/author\\\/patriciot\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MT: De Babel a Metr\u00f3polis - Trusted Translations","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trustedtranslations.com\/es\/blog\/mt-de-babel-a-metropolis","og_locale":"es_ES","og_type":"article","og_title":"MT: De Babel a Metr\u00f3polis - Trusted Translations","og_description":"Como una reflexi\u00f3n acerca de una de las primeras exploraciones cinematogr\u00e1ficas sobre la relaci\u00f3n entre tecnolog\u00eda y humanidad, la pel\u00edcula Metr\u00f3polis (considerada como una de las primeras del g\u00e9nero ciencia...","og_url":"https:\/\/www.trustedtranslations.com\/es\/blog\/mt-de-babel-a-metropolis","og_site_name":"Trusted Translations","article_publisher":"https:\/\/www.facebook.com\/Trusted.Translations","article_modified_time":"2023-01-26T15:48:18+00:00","og_image":[{"width":216,"height":94,"url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/06\/tt-logo-2-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@TrustedT9ns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/mt-de-babel-a-metropolis#article","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/mt-de-babel-a-metropolis"},"author":{"name":"patriciot","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/1fc8d0c2afab85b7c11a12900981da82"},"headline":"MT: De Babel a Metr\u00f3polis","datePublished":"2018-11-03T13:52:44+00:00","dateModified":"2023-01-26T15:48:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/mt-de-babel-a-metropolis"},"wordCount":880,"commentCount":0,"publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"articleSection":["Para Traductores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/mt-de-babel-a-metropolis#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/mt-de-babel-a-metropolis","url":"https:\/\/www.trustedtranslations.com\/es\/blog\/mt-de-babel-a-metropolis","name":"MT: De Babel a Metr\u00f3polis - Trusted Translations","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/mt-de-babel-a-metropolis#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/mt-de-babel-a-metropolis"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/mt-de-babel-a-metropolis#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trustedtranslations.com\/es"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.trustedtranslations.com\/es\/blog"},{"@type":"ListItem","position":3,"name":"Para Traductores","item":"https:\/\/www.trustedtranslations.com\/es\/blog\/categorias\/para-traductores"},{"@type":"ListItem","position":4,"name":"MT: De Babel a Metr\u00f3polis"}]},{"@type":"WebSite","@id":"https:\/\/www.trustedtranslations.com\/es\/#website","url":"https:\/\/www.trustedtranslations.com\/es\/","name":"Trusted Translations, Inc.","description":"Leader in translation and interpretation services.","publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"alternateName":"Trusted Translations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trustedtranslations.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.trustedtranslations.com\/es\/#organization","name":"Trusted Translations","alternateName":"Trusted Translations, Inc.","url":"https:\/\/www.trustedtranslations.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","contentUrl":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","width":500,"height":196,"caption":"Trusted Translations"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Trusted.Translations","https:\/\/x.com\/TrustedT9ns","https:\/\/www.linkedin.com\/company\/trusted-translations"]},{"@type":"Person","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/1fc8d0c2afab85b7c11a12900981da82","name":"patriciot","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"patriciot"},"url":"https:\/\/www.trustedtranslations.com\/es\/author\/patriciot"}]}},"toolset-meta":{"cpt-for-blogs":{"revisor":{"type":"textfield","raw":""},"revisor-image":{"type":"image","raw":"","attachment_id":null},"revisor-description":{"type":"textfield","raw":""},"revisor-link":{"type":"url","raw":""}}},"_links":{"self":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/113522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/comments?post=113522"}],"version-history":[{"count":0,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/113522\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/media?parent=113522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/categories?post=113522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/tags?post=113522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}