{"id":113716,"date":"2017-08-02T12:54:49","date_gmt":"2017-08-02T12:54:49","guid":{"rendered":"https:\/\/www.trustedtranslations.com\/?p=113716"},"modified":"2023-01-26T12:56:21","modified_gmt":"2023-01-26T15:56:21","slug":"estamos-obligados-respetar-las-normas","status":"publish","type":"blog","link":"https:\/\/www.trustedtranslations.com\/es\/blog\/estamos-obligados-respetar-las-normas","title":{"rendered":"\u00bfEstamos obligados a respetar las normas?"},"content":{"rendered":"<p>La idea de que existan normas es que no vivamos en el caos, sino en una sociedad ordenada. En el caso de las normas ling\u00fc\u00edsticas, lo que se busca es que podamos transmitir nuestras ideas con claridad y comunicarnos sin problemas. Pero \u00bfdebemos respetarlas siempre, m\u00e1s all\u00e1 del tipo de texto con el que estemos trabajando? Probablemente, sin pensarlo mucho, lo primero que respondamos sea que \u201cS\u00ed, por supuesto; si no, \u00bfpara qu\u00e9 est\u00e1n las normas?\u201d. Sin embargo, si lo pensamos un poco m\u00e1s, quiz\u00e1 cambiemos de opini\u00f3n.<\/p>\n<p>Supongamos que estamos a punto de alquilar un departamento y debemos firmar el contrato. Lo primero con lo que nos vamos a encontrar es un p\u00e1rrafo largu\u00edsimo en el que se detallan los datos de LAS PARTES, que son el LOCADOR y el LOCATARIO. M\u00e1s adelante, seguro encontremos el n\u00famero de la ley que rige la firma de ese contrato, por ejemplo, la \u201cLey de Propiedad Horizontal N.\u00b0\u00a013.512\u201d. Normativamente, en un solo p\u00e1rrafo y en el n\u00famero de la ley, nos encontramos con varios problemas.<\/p>\n<ol>\n<li>La longitud del p\u00e1rrafo y el uso de un p\u00e1rrafo compuesto por una sola oraci\u00f3n.<br \/>En general, para facilitar la lectura y la comprensi\u00f3n, se recomienda el uso de p\u00e1rrafos compuestos por varias oraciones.<\/li>\n<li>El uso incorrecto de los resaltes ortotipogr\u00e1ficos.<br \/>Normativamente, no hay motivo para resaltar las partes que intervienen en el contrato, con escribir \u201cel locador\u201d, \u201cel locatario\u201d y \u201clas partes\u201d es suficiente.<\/li>\n<li>La escritura del n\u00famero de la ley.<br \/>Seg\u00fan las normas de la RAE, los n\u00fameros que no representan cantidades (a\u00f1os, c\u00f3digos postales, n\u00fameros de leyes, por ejemplo) se escriben sin puntos ni blancos de separaci\u00f3n; sin embargo, en muchos pa\u00edses, los n\u00fameros de las leyes se escriben con punto y aparecen as\u00ed en las publicaciones oficiales.<\/li>\n<\/ol>\n<p>Imaginemos ahora que estamos leyendo un manual para empleados destinado a hablantes de espa\u00f1ol que viven en Estados Unidos. Si bien la norma establece que solo la inicial de la primera letra de un t\u00edtulo se escribe con <a href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/punto-de-negociacion-el-uso-de-las-mayusculas-primera-parte\">may\u00fascula<\/a>, podemos encontrarnos, por ejemplo, con un t\u00edtulo como este: <em>Pol\u00edticas de Uso de los Dispositivos Electr\u00f3nicos<\/em>. Estar\u00edamos en presencia de un anglicismo ortotipogr\u00e1fico. Tambi\u00e9n es probable que nos encontremos con una oraci\u00f3n como <em>En el 85% de los casos, no es necesario que utilice su tel\u00e9fono celular <\/em>aunque lo normativo sea que el <a href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/como-escribir-correctamente-los-simbolos\">s\u00edmbolo de porcentaje<\/a> vaya separado de la cifra con un <a href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/espacio-no-separacion\">espacio de no separaci\u00f3n<\/a>.<\/p>\n<p>En estos casos, lo mejor es analizar de qu\u00e9 tipo de texto se trata y a qui\u00e9n va dirigido para, luego, determinar los par\u00e1metros con los que nos vamos a manejar. En el contrato, seguramente respetemos los resaltes ortotipogr\u00e1ficos que eligi\u00f3 el abogado que lo redact\u00f3 y dejemos el n\u00famero de la ley como figura en todas las publicaciones que la mencionan. En el segundo ejemplo, lo m\u00e1s probable es que sea una traducci\u00f3n de un texto en ingl\u00e9s y que el cliente haya dado instrucciones de que se respete la puntuaci\u00f3n del ingl\u00e9s. Quiz\u00e1, en estos textos, solo podamos limitarnos a corregir la ortograf\u00eda.<\/p>\n<p>Quienes nos dedicamos a la <a href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/la-importancia-contar-traductores-e-interpretes-profesionales-2016-09-28.html\">traducci\u00f3n<\/a> y a la correcci\u00f3n debemos conocer en profundidad la normativa de las lenguas con las que trabajamos y respetarla siempre que sea posible. Sin embargo, tambi\u00e9n debemos tener la capacidad de adaptarnos a los diferentes g\u00e9neros discursivos, a las tradiciones de cada disciplina, al destinatario y a las exigencias de los clientes. Despu\u00e9s de todo, para romper las reglas, primero hay que conocerlas.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"La idea de que existan normas es que no vivamos en el caos, sino en una sociedad ordenada. En el caso de las normas ling\u00fc\u00edsticas, lo que se busca es\u2026\n","protected":false},"author":76,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8893],"tags":[9142,9202,8834,9203],"class_list":["post-113716","blog","type-blog","status-publish","format-standard","hentry","category-para-traductores","tag-cliente","tag-mayusculas","tag-normas","tag-normativa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfEstamos obligados a respetar las normas? - Trusted Translations<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/estamos-obligados-respetar-las-normas\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfEstamos obligados a respetar las normas? - Trusted Translations\" \/>\n<meta property=\"og:description\" content=\"La idea de que existan normas es que no vivamos en el caos, sino en una sociedad ordenada. En el caso de las normas ling\u00fc\u00edsticas, lo que se busca es...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trustedtranslations.com\/es\/blog\/estamos-obligados-respetar-las-normas\" \/>\n<meta property=\"og:site_name\" content=\"Trusted Translations\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Trusted.Translations\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-26T15:56:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/06\/tt-logo-2-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"216\" \/>\n\t<meta property=\"og:image:height\" content=\"94\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TrustedT9ns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/estamos-obligados-respetar-las-normas#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/estamos-obligados-respetar-las-normas\"},\"author\":{\"name\":\"veronicav\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/41f85d8abe52b781bc1dba6698c016da\"},\"headline\":\"\u00bfEstamos obligados a respetar las normas?\",\"datePublished\":\"2017-08-02T12:54:49+00:00\",\"dateModified\":\"2023-01-26T15:56:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/estamos-obligados-respetar-las-normas\"},\"wordCount\":634,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"keywords\":[\"cliente\",\"may\u00fasculas\",\"normas\",\"normativa\"],\"articleSection\":[\"Para Traductores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/estamos-obligados-respetar-las-normas#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/estamos-obligados-respetar-las-normas\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/estamos-obligados-respetar-las-normas\",\"name\":\"\u00bfEstamos obligados a respetar las normas? - Trusted Translations\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/estamos-obligados-respetar-las-normas#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/estamos-obligados-respetar-las-normas\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/estamos-obligados-respetar-las-normas#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sin categorizar\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/categorias\\\/sin-categorizar\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u00bfEstamos obligados a respetar las normas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"name\":\"Trusted Translations, Inc.\",\"description\":\"Leader in translation and interpretation services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"alternateName\":\"Trusted Translations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\",\"name\":\"Trusted Translations\",\"alternateName\":\"Trusted Translations, Inc.\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"contentUrl\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"width\":500,\"height\":196,\"caption\":\"Trusted Translations\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Trusted.Translations\",\"https:\\\/\\\/x.com\\\/TrustedT9ns\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/trusted-translations\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/41f85d8abe52b781bc1dba6698c016da\",\"name\":\"veronicav\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"veronicav\"},\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/author\\\/veronicav\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfEstamos obligados a respetar las normas? - Trusted Translations","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trustedtranslations.com\/es\/blog\/estamos-obligados-respetar-las-normas","og_locale":"es_ES","og_type":"article","og_title":"\u00bfEstamos obligados a respetar las normas? - Trusted Translations","og_description":"La idea de que existan normas es que no vivamos en el caos, sino en una sociedad ordenada. En el caso de las normas ling\u00fc\u00edsticas, lo que se busca es...","og_url":"https:\/\/www.trustedtranslations.com\/es\/blog\/estamos-obligados-respetar-las-normas","og_site_name":"Trusted Translations","article_publisher":"https:\/\/www.facebook.com\/Trusted.Translations","article_modified_time":"2023-01-26T15:56:21+00:00","og_image":[{"width":216,"height":94,"url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/06\/tt-logo-2-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@TrustedT9ns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/estamos-obligados-respetar-las-normas#article","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/estamos-obligados-respetar-las-normas"},"author":{"name":"veronicav","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/41f85d8abe52b781bc1dba6698c016da"},"headline":"\u00bfEstamos obligados a respetar las normas?","datePublished":"2017-08-02T12:54:49+00:00","dateModified":"2023-01-26T15:56:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/estamos-obligados-respetar-las-normas"},"wordCount":634,"commentCount":0,"publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"keywords":["cliente","may\u00fasculas","normas","normativa"],"articleSection":["Para Traductores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/estamos-obligados-respetar-las-normas#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/estamos-obligados-respetar-las-normas","url":"https:\/\/www.trustedtranslations.com\/es\/blog\/estamos-obligados-respetar-las-normas","name":"\u00bfEstamos obligados a respetar las normas? - Trusted Translations","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/estamos-obligados-respetar-las-normas#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/estamos-obligados-respetar-las-normas"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/estamos-obligados-respetar-las-normas#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trustedtranslations.com\/es"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.trustedtranslations.com\/es\/blog"},{"@type":"ListItem","position":3,"name":"Sin categorizar","item":"https:\/\/www.trustedtranslations.com\/es\/blog\/categorias\/sin-categorizar"},{"@type":"ListItem","position":4,"name":"\u00bfEstamos obligados a respetar las normas?"}]},{"@type":"WebSite","@id":"https:\/\/www.trustedtranslations.com\/es\/#website","url":"https:\/\/www.trustedtranslations.com\/es\/","name":"Trusted Translations, Inc.","description":"Leader in translation and interpretation services.","publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"alternateName":"Trusted Translations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trustedtranslations.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.trustedtranslations.com\/es\/#organization","name":"Trusted Translations","alternateName":"Trusted Translations, Inc.","url":"https:\/\/www.trustedtranslations.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","contentUrl":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","width":500,"height":196,"caption":"Trusted Translations"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Trusted.Translations","https:\/\/x.com\/TrustedT9ns","https:\/\/www.linkedin.com\/company\/trusted-translations"]},{"@type":"Person","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/41f85d8abe52b781bc1dba6698c016da","name":"veronicav","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"veronicav"},"url":"https:\/\/www.trustedtranslations.com\/es\/author\/veronicav"}]}},"toolset-meta":{"cpt-for-blogs":{"revisor":{"type":"textfield","raw":""},"revisor-image":{"type":"image","raw":"","attachment_id":null},"revisor-description":{"type":"textfield","raw":""},"revisor-link":{"type":"url","raw":""}}},"_links":{"self":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/113716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/users\/76"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/comments?post=113716"}],"version-history":[{"count":0,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/113716\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/media?parent=113716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/categories?post=113716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/tags?post=113716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}