{"id":113916,"date":"2016-08-24T14:49:09","date_gmt":"2016-08-24T14:49:09","guid":{"rendered":"https:\/\/www.trustedtranslations.com\/?p=113916"},"modified":"2023-01-26T12:59:06","modified_gmt":"2023-01-26T15:59:06","slug":"faltan-traductores-la-carrera-presidencial-ee-uu","status":"publish","type":"blog","link":"https:\/\/www.trustedtranslations.com\/es\/blog\/faltan-traductores-la-carrera-presidencial-ee-uu","title":{"rendered":"\u00a1SOS! Faltan traductores en la carrera presidencial de EE. UU."},"content":{"rendered":"<p>En una campa\u00f1a presidencial tan inusual por tantos motivos, no sorprende que el papel de los extranjeros en ella haya tra\u00eddo aparejado cierta reprobaci\u00f3n, ling\u00fc\u00edsticamente hablando. Y antes de que las aguas se calmen tras el esc\u00e1ndalo del presunto plagio por parte de la esposa del candidato republicano de la actual primera dama, cuando \u00e9sta se pronunci\u00f3 en la Convenci\u00f3n Dem\u00f3crata de Denver en 2008, la opini\u00f3n p\u00fablica de Estados Unidos (y m\u00e1s all\u00e1, puesto que \u2014acept\u00e9moslo\u2014 en estas elecciones no solo est\u00e1 en juego el futuro de los estadounidenses) se desayun\u00f3 con un nuevo fest\u00edn proveniente del Partido Republicano.<\/p>\n<p>La Convenci\u00f3n Nacional Republicana cerr\u00f3 la semana pasada con un discurso del candidato a presidente Donald Trump, pero algunos observadores expresaron cierta perplejidad por los mal traducidos carteles que rezaban \u201cLatinos Para Trump\u201d en manos de algunas personas de la multitud.<\/p>\n<p>No se trataba de un pu\u00f1ado de partidarios autoconvocados con pancartas hechas a mano, hab\u00eda cientos de estos carteles impresos por la propia campa\u00f1a republicana.<\/p>\n<p>Y, si bien el espa\u00f1ol es la segunda lengua m\u00e1s hablada del pa\u00eds, incluso entre los no hispanos, parece que algunos de los responsables de la campa\u00f1a republicana faltaron a algunas clases. \u00bfSer\u00e1 as\u00ed?<\/p>\n<p>Ocurre que la mala prensa ha sido un muy eficaz fertilizante para la popularidad del candidato republicano. Y teniendo en cuenta Donald Trump viene del mundo de los negocios, donde la fuerza que insiste en imponer su l\u00f3gica se llama mercado, no estar\u00eda de m\u00e1s recordar aquella m\u00e1xima del <em>contramarketing<\/em> que sostiene que no existe tal cosa como la mala publicidad.<\/p>\n<p>Parece que quienes intentaron traducir el mensaje original (en ingl\u00e9s), usaron la palabra \u201cpara\u201d en lugar de \u201cpor\u201d. Ambas preposiciones en ingl\u00e9s se traducen como \u201cfor\u201d, pero son usadas con fines bien diferentes.<\/p>\n<p>Si bien puede ser f\u00e1cil confundir las palabras \u201cpara\u201d y \u201cpor\u201d, sin duda hay una amplia diferencia gramatical. Si uno quisiera manifestar apoyo por alguien a trav\u00e9s del voto, deber\u00eda usar la preposici\u00f3n \u201cpor\u201d. \u201cPara\u201d no tiene sentido en ese contexto, a menos que desee expresar que quien sostiene el cartel trabaja para la persona aludida en el mismo, por ejemplo (una torpeza que podr\u00eda resultar completamente antip\u00e1tica para alguien conocido no solo por contratar sino tambi\u00e9n por despedir empleados, incluso en programas de TV).<\/p>\n<p>Otros pusieron en duda que las personas que sosten\u00edan las pancartas fueran en efecto hispanas. Independientemente de qui\u00e9n sosten\u00eda los carteles, alguien tendr\u00e1 que revisar sus apuntes de espa\u00f1ol b\u00e1sico, volver a mandar a imprimir los carteles o ambas. Tampoco estar\u00eda de m\u00e1s destacar que la preposici\u00f3n utilizada en los carteles tambi\u00e9n corresponde a una conjugaci\u00f3n del verbo \u201cparar\u201d. \u00bfSer\u00e1 esta una profec\u00eda autocumplida?<\/p>\n<p>No permita que esta entrada lo convenza de que se trata de una columna de opini\u00f3n sobre el Partido Republicano; en mi pr\u00f3xima publicaci\u00f3n, los Dem\u00f3cratas recibir\u00e1n su parte.<\/p>\n","protected":false},"excerpt":{"rendered":"En una campa\u00f1a presidencial tan inusual por tantos motivos, no sorprende que el papel de los extranjeros en ella haya tra\u00eddo aparejado cierta reprobaci\u00f3n, ling\u00fc\u00edsticamente hablando. Y antes de que\u2026\n","protected":false},"author":62,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8893],"tags":[9419,9417,9420,9418],"class_list":["post-113916","blog","type-blog","status-publish","format-standard","hentry","category-para-traductores","tag-campana-presidencial","tag-contramarketing","tag-partidarios","tag-preposiciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1SOS! Faltan traductores en la carrera presidencial de EE. UU. - Trusted Translations<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/faltan-traductores-la-carrera-presidencial-ee-uu\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1SOS! Faltan traductores en la carrera presidencial de EE. UU. - Trusted Translations\" \/>\n<meta property=\"og:description\" content=\"En una campa\u00f1a presidencial tan inusual por tantos motivos, no sorprende que el papel de los extranjeros en ella haya tra\u00eddo aparejado cierta reprobaci\u00f3n, ling\u00fc\u00edsticamente hablando. Y antes de que...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trustedtranslations.com\/es\/blog\/faltan-traductores-la-carrera-presidencial-ee-uu\" \/>\n<meta property=\"og:site_name\" content=\"Trusted Translations\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Trusted.Translations\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-26T15:59:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/06\/tt-logo-2-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"216\" \/>\n\t<meta property=\"og:image:height\" content=\"94\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TrustedT9ns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/faltan-traductores-la-carrera-presidencial-ee-uu#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/faltan-traductores-la-carrera-presidencial-ee-uu\"},\"author\":{\"name\":\"nicolasl\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/451ada4f8ff3208960e108f513f119e0\"},\"headline\":\"\u00a1SOS! Faltan traductores en la carrera presidencial de EE. UU.\",\"datePublished\":\"2016-08-24T14:49:09+00:00\",\"dateModified\":\"2023-01-26T15:59:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/faltan-traductores-la-carrera-presidencial-ee-uu\"},\"wordCount\":530,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"keywords\":[\"campa\u00f1a presidencial\",\"contramarketing\",\"partidarios\",\"preposiciones\"],\"articleSection\":[\"Para Traductores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/faltan-traductores-la-carrera-presidencial-ee-uu#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/faltan-traductores-la-carrera-presidencial-ee-uu\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/faltan-traductores-la-carrera-presidencial-ee-uu\",\"name\":\"\u00a1SOS! Faltan traductores en la carrera presidencial de EE. UU. - Trusted Translations\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/faltan-traductores-la-carrera-presidencial-ee-uu#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/faltan-traductores-la-carrera-presidencial-ee-uu\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/faltan-traductores-la-carrera-presidencial-ee-uu#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sin categorizar\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/categorias\\\/sin-categorizar\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u00a1SOS! Faltan traductores en la carrera presidencial de EE. UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"name\":\"Trusted Translations, Inc.\",\"description\":\"Leader in translation and interpretation services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"alternateName\":\"Trusted Translations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\",\"name\":\"Trusted Translations\",\"alternateName\":\"Trusted Translations, Inc.\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"contentUrl\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"width\":500,\"height\":196,\"caption\":\"Trusted Translations\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Trusted.Translations\",\"https:\\\/\\\/x.com\\\/TrustedT9ns\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/trusted-translations\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/451ada4f8ff3208960e108f513f119e0\",\"name\":\"nicolasl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"nicolasl\"},\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/author\\\/nicolasl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1SOS! Faltan traductores en la carrera presidencial de EE. UU. - Trusted Translations","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trustedtranslations.com\/es\/blog\/faltan-traductores-la-carrera-presidencial-ee-uu","og_locale":"es_ES","og_type":"article","og_title":"\u00a1SOS! Faltan traductores en la carrera presidencial de EE. UU. - Trusted Translations","og_description":"En una campa\u00f1a presidencial tan inusual por tantos motivos, no sorprende que el papel de los extranjeros en ella haya tra\u00eddo aparejado cierta reprobaci\u00f3n, ling\u00fc\u00edsticamente hablando. Y antes de que...","og_url":"https:\/\/www.trustedtranslations.com\/es\/blog\/faltan-traductores-la-carrera-presidencial-ee-uu","og_site_name":"Trusted Translations","article_publisher":"https:\/\/www.facebook.com\/Trusted.Translations","article_modified_time":"2023-01-26T15:59:06+00:00","og_image":[{"width":216,"height":94,"url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/06\/tt-logo-2-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@TrustedT9ns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/faltan-traductores-la-carrera-presidencial-ee-uu#article","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/faltan-traductores-la-carrera-presidencial-ee-uu"},"author":{"name":"nicolasl","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/451ada4f8ff3208960e108f513f119e0"},"headline":"\u00a1SOS! Faltan traductores en la carrera presidencial de EE. UU.","datePublished":"2016-08-24T14:49:09+00:00","dateModified":"2023-01-26T15:59:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/faltan-traductores-la-carrera-presidencial-ee-uu"},"wordCount":530,"commentCount":0,"publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"keywords":["campa\u00f1a presidencial","contramarketing","partidarios","preposiciones"],"articleSection":["Para Traductores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/faltan-traductores-la-carrera-presidencial-ee-uu#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/faltan-traductores-la-carrera-presidencial-ee-uu","url":"https:\/\/www.trustedtranslations.com\/es\/blog\/faltan-traductores-la-carrera-presidencial-ee-uu","name":"\u00a1SOS! Faltan traductores en la carrera presidencial de EE. UU. - Trusted Translations","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/faltan-traductores-la-carrera-presidencial-ee-uu#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/faltan-traductores-la-carrera-presidencial-ee-uu"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/faltan-traductores-la-carrera-presidencial-ee-uu#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trustedtranslations.com\/es"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.trustedtranslations.com\/es\/blog"},{"@type":"ListItem","position":3,"name":"Sin categorizar","item":"https:\/\/www.trustedtranslations.com\/es\/blog\/categorias\/sin-categorizar"},{"@type":"ListItem","position":4,"name":"\u00a1SOS! Faltan traductores en la carrera presidencial de EE. UU."}]},{"@type":"WebSite","@id":"https:\/\/www.trustedtranslations.com\/es\/#website","url":"https:\/\/www.trustedtranslations.com\/es\/","name":"Trusted Translations, Inc.","description":"Leader in translation and interpretation services.","publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"alternateName":"Trusted Translations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trustedtranslations.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.trustedtranslations.com\/es\/#organization","name":"Trusted Translations","alternateName":"Trusted Translations, Inc.","url":"https:\/\/www.trustedtranslations.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","contentUrl":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","width":500,"height":196,"caption":"Trusted Translations"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Trusted.Translations","https:\/\/x.com\/TrustedT9ns","https:\/\/www.linkedin.com\/company\/trusted-translations"]},{"@type":"Person","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/451ada4f8ff3208960e108f513f119e0","name":"nicolasl","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"nicolasl"},"url":"https:\/\/www.trustedtranslations.com\/es\/author\/nicolasl"}]}},"toolset-meta":{"cpt-for-blogs":{"revisor":{"type":"textfield","raw":""},"revisor-image":{"type":"image","raw":"","attachment_id":null},"revisor-description":{"type":"textfield","raw":""},"revisor-link":{"type":"url","raw":""}}},"_links":{"self":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/113916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/comments?post=113916"}],"version-history":[{"count":0,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/113916\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/media?parent=113916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/categories?post=113916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/tags?post=113916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}