{"id":114027,"date":"2015-12-16T08:46:08","date_gmt":"2015-12-16T08:46:08","guid":{"rendered":"https:\/\/www.trustedtranslations.com\/?p=114027"},"modified":"2023-01-26T13:00:41","modified_gmt":"2023-01-26T16:00:41","slug":"nuevos-terminos-para-traducir-click-farms","status":"publish","type":"blog","link":"https:\/\/www.trustedtranslations.com\/es\/blog\/nuevos-terminos-para-traducir-click-farms","title":{"rendered":"Nuevos t\u00e9rminos para traducir: click-farms"},"content":{"rendered":"<p>En <a href=\"https:\/\/www.trustedtranslations.com\" target=\"_blank\" rel=\"noopener\"><em><em>Trusted Translations<\/em><\/em><\/a> nos preguntamos con bastante frecuencia c\u00f3mo se traducir\u00eda tal o cual t\u00e9rmino. Por lo general, la extensi\u00f3n de nuestros debates es directamente proporcional a lo novedoso de estos t\u00e9rminos. Dicho de otro modo, suele haber m\u00e1s consenso cuanto menos actual es la expresi\u00f3n o categor\u00eda a traducir.<\/p>\n<p>Son tan numerosas las miradas que proponemos desde esta p\u00e1gina a temas relativos a la traducci\u00f3n, los idiomas, etc. que las posibilidades de nuevos abordajes no parecen exactamente multiplicarse. Tal es as\u00ed que empezamos a analizar la posibilidad, aunque solo fuera en chiste, de tercerizar la redacci\u00f3n de estos art\u00edculos a cambio de dinero, sin renunciar a nuestra (falaz) autor\u00eda.<\/p>\n<p>Es as\u00ed como empezamos a hablar de un t\u00e9rmino que caracterizar\u00eda esta tarea de escritura en las sombras, que en ingl\u00e9s se denomina <em>ghost-writer<\/em>. Se trata de escritores que generan material para otros que solamente ponen su firma. El t\u00e9rmino no se aplica exclusivamente a la escritura, sino que est\u00e1 presente en diversas ramas de la industria cultural como la m\u00fasica por ejemplo. Surgido en los \u00faltimos a\u00f1os, este rol marca el origen de la fisura que resquebraja el halo meritocr\u00e1tico que caracteriz\u00f3 a internet en los \u00faltimos tiempos.<\/p>\n<p>Y hablando de la crisis de la meritocracia en internet llegamos a un t\u00e9rmino bastante complicado de traducir: las <em>click-farms<\/em>. Se trata de emprendimientos mayormente radicados en pa\u00edses del sudeste asi\u00e1tico dedicados a enaltecer cualquier contenido alojado en la red. Una canci\u00f3n, esta entrada de este blog, una foto en una red social, cualquier cosa es pasible de ser elogiada, ponderada o celebrada con <em>likes<\/em>, <em>shares <\/em>o comentarios.<\/p>\n<p>Entonces, \u00bfc\u00f3mo habremos de denominar estos nuevos emprendimientos en espa\u00f1ol? Y, \u00bfqui\u00e9nes son las personas que se manifiestan a favor de estos contenidos? Una breve investigaci\u00f3n permite\u00a0determinar que se trata de perfiles ap\u00f3crifos comandados por empleados de estas <em>click-farms<\/em> quienes trabajan de aduladores seriales del contenido que fuera. Es as\u00ed como se conform\u00f3 un sinn\u00famero de emprendimientos que prestan estos servicios, en muchos casos de forma anexa a las redes en las que operan, que tienen la capacidad de convertir\u00a0una foto, una canci\u00f3n, un mero estado o un texto intrascendentes en contenido de alta circulaci\u00f3n. Se sabe que un contenido muy elogiado mediante los mecanismos previstos por la red que los aloja le confiere una mayor circulaci\u00f3n entre las p\u00e1ginas de inicio (<em>feeds<\/em>) de los usuarios de dicha red.<\/p>\n<p>Como dice en el primer p\u00e1rrafo, el t\u00e9rmino es muy nuevo a\u00fan como para que se hayan homologado equivalencias en otros idiomas. Personalmente descartar\u00eda cualquier opci\u00f3n literal\u00a0y optar\u00eda por una per\u00edfrasis del estilo: <em>usina de viralidad<\/em> o <em>generadores de m\u00e9rito<\/em>.\u00a0Por este tipo de dilemas y muchos m\u00e1s, no dude en contactarse con <a href=\"https:\/\/www.trustedtranslations.com\" target=\"_blank\" rel=\"noopener\"><em><em>Trusted Translations<\/em><\/em><\/a> para que lo asesoremos de la mejor manera posible.<\/p>\n","protected":false},"excerpt":{"rendered":"En Trusted Translations nos preguntamos con bastante frecuencia c\u00f3mo se traducir\u00eda tal o cual t\u00e9rmino. Por lo general, la extensi\u00f3n de nuestros debates es directamente proporcional a lo novedoso de\u2026\n","protected":false},"author":62,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8893],"tags":[8892,7583,8972],"class_list":["post-114027","blog","type-blog","status-publish","format-standard","hentry","category-para-traductores","tag-idiomas","tag-internet","tag-traduccion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuevos t\u00e9rminos para traducir: click-farms - Trusted Translations<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/nuevos-terminos-para-traducir-click-farms\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevos t\u00e9rminos para traducir: click-farms - Trusted Translations\" \/>\n<meta property=\"og:description\" content=\"En Trusted Translations nos preguntamos con bastante frecuencia c\u00f3mo se traducir\u00eda tal o cual t\u00e9rmino. Por lo general, la extensi\u00f3n de nuestros debates es directamente proporcional a lo novedoso de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trustedtranslations.com\/es\/blog\/nuevos-terminos-para-traducir-click-farms\" \/>\n<meta property=\"og:site_name\" content=\"Trusted Translations\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Trusted.Translations\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-26T16:00:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/06\/tt-logo-2-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"216\" \/>\n\t<meta property=\"og:image:height\" content=\"94\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TrustedT9ns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/nuevos-terminos-para-traducir-click-farms#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/nuevos-terminos-para-traducir-click-farms\"},\"author\":{\"name\":\"nicolasl\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/451ada4f8ff3208960e108f513f119e0\"},\"headline\":\"Nuevos t\u00e9rminos para traducir: click-farms\",\"datePublished\":\"2015-12-16T08:46:08+00:00\",\"dateModified\":\"2023-01-26T16:00:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/nuevos-terminos-para-traducir-click-farms\"},\"wordCount\":512,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"keywords\":[\"idiomas\",\"internet\",\"traducci\u00f3n\"],\"articleSection\":[\"Para Traductores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/nuevos-terminos-para-traducir-click-farms#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/nuevos-terminos-para-traducir-click-farms\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/nuevos-terminos-para-traducir-click-farms\",\"name\":\"Nuevos t\u00e9rminos para traducir: click-farms - Trusted Translations\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/nuevos-terminos-para-traducir-click-farms#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/nuevos-terminos-para-traducir-click-farms\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/nuevos-terminos-para-traducir-click-farms#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Para Traductores\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/categorias\\\/para-traductores\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Nuevos t\u00e9rminos para traducir: click-farms\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"name\":\"Trusted Translations, Inc.\",\"description\":\"Leader in translation and interpretation services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"alternateName\":\"Trusted Translations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\",\"name\":\"Trusted Translations\",\"alternateName\":\"Trusted Translations, Inc.\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"contentUrl\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"width\":500,\"height\":196,\"caption\":\"Trusted Translations\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Trusted.Translations\",\"https:\\\/\\\/x.com\\\/TrustedT9ns\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/trusted-translations\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/451ada4f8ff3208960e108f513f119e0\",\"name\":\"nicolasl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"nicolasl\"},\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/author\\\/nicolasl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevos t\u00e9rminos para traducir: click-farms - Trusted Translations","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trustedtranslations.com\/es\/blog\/nuevos-terminos-para-traducir-click-farms","og_locale":"es_ES","og_type":"article","og_title":"Nuevos t\u00e9rminos para traducir: click-farms - Trusted Translations","og_description":"En Trusted Translations nos preguntamos con bastante frecuencia c\u00f3mo se traducir\u00eda tal o cual t\u00e9rmino. Por lo general, la extensi\u00f3n de nuestros debates es directamente proporcional a lo novedoso de...","og_url":"https:\/\/www.trustedtranslations.com\/es\/blog\/nuevos-terminos-para-traducir-click-farms","og_site_name":"Trusted Translations","article_publisher":"https:\/\/www.facebook.com\/Trusted.Translations","article_modified_time":"2023-01-26T16:00:41+00:00","og_image":[{"width":216,"height":94,"url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/06\/tt-logo-2-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@TrustedT9ns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/nuevos-terminos-para-traducir-click-farms#article","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/nuevos-terminos-para-traducir-click-farms"},"author":{"name":"nicolasl","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/451ada4f8ff3208960e108f513f119e0"},"headline":"Nuevos t\u00e9rminos para traducir: click-farms","datePublished":"2015-12-16T08:46:08+00:00","dateModified":"2023-01-26T16:00:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/nuevos-terminos-para-traducir-click-farms"},"wordCount":512,"commentCount":0,"publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"keywords":["idiomas","internet","traducci\u00f3n"],"articleSection":["Para Traductores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/nuevos-terminos-para-traducir-click-farms#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/nuevos-terminos-para-traducir-click-farms","url":"https:\/\/www.trustedtranslations.com\/es\/blog\/nuevos-terminos-para-traducir-click-farms","name":"Nuevos t\u00e9rminos para traducir: click-farms - Trusted Translations","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/nuevos-terminos-para-traducir-click-farms#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/nuevos-terminos-para-traducir-click-farms"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/nuevos-terminos-para-traducir-click-farms#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trustedtranslations.com\/es"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.trustedtranslations.com\/es\/blog"},{"@type":"ListItem","position":3,"name":"Para Traductores","item":"https:\/\/www.trustedtranslations.com\/es\/blog\/categorias\/para-traductores"},{"@type":"ListItem","position":4,"name":"Nuevos t\u00e9rminos para traducir: click-farms"}]},{"@type":"WebSite","@id":"https:\/\/www.trustedtranslations.com\/es\/#website","url":"https:\/\/www.trustedtranslations.com\/es\/","name":"Trusted Translations, Inc.","description":"Leader in translation and interpretation services.","publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"alternateName":"Trusted Translations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trustedtranslations.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.trustedtranslations.com\/es\/#organization","name":"Trusted Translations","alternateName":"Trusted Translations, Inc.","url":"https:\/\/www.trustedtranslations.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","contentUrl":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","width":500,"height":196,"caption":"Trusted Translations"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Trusted.Translations","https:\/\/x.com\/TrustedT9ns","https:\/\/www.linkedin.com\/company\/trusted-translations"]},{"@type":"Person","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/451ada4f8ff3208960e108f513f119e0","name":"nicolasl","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"nicolasl"},"url":"https:\/\/www.trustedtranslations.com\/es\/author\/nicolasl"}]}},"toolset-meta":{"cpt-for-blogs":{"revisor":{"type":"textfield","raw":""},"revisor-image":{"type":"image","raw":"","attachment_id":null},"revisor-description":{"type":"textfield","raw":""},"revisor-link":{"type":"url","raw":""}}},"_links":{"self":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/114027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/comments?post=114027"}],"version-history":[{"count":0,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/114027\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/media?parent=114027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/categories?post=114027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/tags?post=114027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}