{"id":114396,"date":"2014-05-12T10:00:11","date_gmt":"2014-05-12T10:00:11","guid":{"rendered":"https:\/\/www.trustedtranslations.com\/?p=114396"},"modified":"2023-01-26T13:06:29","modified_gmt":"2023-01-26T16:06:29","slug":"el-misterio-de-un-libro-intraducible","status":"publish","type":"blog","link":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-misterio-de-un-libro-intraducible","title":{"rendered":"El misterio de un libro intraducible"},"content":{"rendered":"<p>En la Biblioteca Beinecke de Manuscritos y Libros Raros de la Universidad de Yale, en Estados Unidos, se encuentra un libro que nadie ha podido leer jam\u00e1s, escrito en un idioma inexistente o desconocido, que presenta ilustraciones de plantas y criaturas que nunca se han visto en el planeta. El ejemplar tiene 240 p\u00e1ginas ilustradas, es bastante peque\u00f1o y est\u00e1 encuadernado con una d\u00e9bil cubierta de vitela (piel de vaca o ternera que sirve para pintar o escribir sobre ella) de color marfil viejo. En sus p\u00e1ginas se pueden ver plantas ex\u00f3ticas, s\u00edmbolos astrol\u00f3gicos, criaturas con forma de medusas e incluso algo parecido a una langosta. En una de las im\u00e1genes se ve a un grupo de mujeres con piel de alabastro, desnudas, que se deslizan por un tobog\u00e1n de agua. El texto est\u00e1 escrito con letras marrones y el idioma se parece al Elvish, creado por el escritor ingl\u00e9s J. R. R. Tolkien para sus novelas fant\u00e1sticas.<\/p>\n<p>Las teor\u00edas acerca de su origen son numerosas y disparatadas. \u00bfEs un sistema de comunicaci\u00f3n secreto sobre un tesoro enterrado? \u00bfEl manual de un envenenador? \u00bfLa receta codificada para la eterna juventud? Incluso se ha dicho que se trata de un diario ilustrado de un adolescente extraterrestre que lo dej\u00f3 en la Tierra antes de partir.<\/p>\n<p>Este misterioso libro es conocido como \u201cel Manuscrito de Voynich\u201d, en honor al comerciante de libros de segunda mano Wilfrid Voynich, quien dijo haberlo descubierto en Italia en 1912. Se tiene certeza de que Voynich naci\u00f3 en 1865, era de origen polaco y viv\u00eda en Lituania, territorio que en ese entonces pertenec\u00eda al Imperio Ruso. Fue detenido y llevado a Siberia por ejercer actividades revolucionarias y posteriormente huy\u00f3 a Inglaterra a trav\u00e9s de Manchuria. En Londres, estableci\u00f3 una librer\u00eda de textos de segunda mano, que se convirti\u00f3 en un centro donde conflu\u00edan exiliados pol\u00edticos. Voynich dijo que se hab\u00eda topado con el manuscrito en un seminario jesuita, en la Villa Madragone, cerca de Roma.<\/p>\n<p>En el manuscrito se encontraba una carta escrita en 1665 por Johannes Marcus Marci, un f\u00edsico del Sacro Imperio Romano. All\u00ed dec\u00eda que el texto hab\u00eda pertenecido a Rodolfo II, emperador del Sacro Imperio Romano Germ\u00e1nico y que probablemente era obra del alquimista isabelino Roger Bacon. Otros dos posibles autores que suelen vincularse con el misterioso texto son: John Dee, un mago extraordinario y astr\u00f3logo de la reina Isabel, y uno de sus seguidores, Edward Kelley.<\/p>\n<p>Otra teor\u00eda indica que, tal vez, el libro no haya sido descubierto por Voynich, sino que \u00e9l mismo lo haya falsificado aplicando los conocimientos sobre qu\u00edmica que obtuvo en la Universidad de Mosc\u00fa en su paso por Rusia y, utilizando una gran cantidad de pergamino, haya creado el curioso ejemplar.<\/p>\n<p>Desde que se tiene conocimiento de la existencia del libro, muchos especialistas han estado interesados en descifrar su contenido. El estadounidense William Friedman, uno de los grandes cript\u00f3grafos del siglo XX, pas\u00f3 30 a\u00f1os intentando descifrar el c\u00f3digo del manuscrito. Por otra parte, se ha afirmado que las plantas que aparecen son de origen mesoamericano, mientras que otros afirman haber traducido algunas palabras aplicando conocimientos de ling\u00fc\u00edstica. Sin embargo, pese a las numerosas investigaciones y esfuerzos realizados, sigue siendo, al menos por ahora, completamente intraducible.<\/p>\n","protected":false},"excerpt":{"rendered":"En la Biblioteca Beinecke de Manuscritos y Libros Raros de la Universidad de Yale, en Estados Unidos, se encuentra un libro que nadie ha podido leer jam\u00e1s, escrito en un\u2026\n","protected":false},"author":68,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8893],"tags":[9091,8891,9059,9862],"class_list":["post-114396","blog","type-blog","status-publish","format-standard","hentry","category-para-traductores","tag-codigo","tag-comunicacion","tag-idioma","tag-textos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El misterio de un libro intraducible - Trusted Translations<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/el-misterio-de-un-libro-intraducible\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El misterio de un libro intraducible - Trusted Translations\" \/>\n<meta property=\"og:description\" content=\"En la Biblioteca Beinecke de Manuscritos y Libros Raros de la Universidad de Yale, en Estados Unidos, se encuentra un libro que nadie ha podido leer jam\u00e1s, escrito en un...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trustedtranslations.com\/es\/blog\/el-misterio-de-un-libro-intraducible\" \/>\n<meta property=\"og:site_name\" content=\"Trusted Translations\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Trusted.Translations\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-26T16:06:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/06\/tt-logo-2-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"216\" \/>\n\t<meta property=\"og:image:height\" content=\"94\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TrustedT9ns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-misterio-de-un-libro-intraducible#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-misterio-de-un-libro-intraducible\"},\"author\":{\"name\":\"clegnazzi\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/fa7711d1d5a1a786b05cf22fb72afc46\"},\"headline\":\"El misterio de un libro intraducible\",\"datePublished\":\"2014-05-12T10:00:11+00:00\",\"dateModified\":\"2023-01-26T16:06:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-misterio-de-un-libro-intraducible\"},\"wordCount\":572,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"keywords\":[\"c\u00f3digo\",\"comunicaci\u00f3n\",\"idioma\",\"textos\"],\"articleSection\":[\"Para Traductores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-misterio-de-un-libro-intraducible#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-misterio-de-un-libro-intraducible\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-misterio-de-un-libro-intraducible\",\"name\":\"El misterio de un libro intraducible - Trusted Translations\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-misterio-de-un-libro-intraducible#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-misterio-de-un-libro-intraducible\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-misterio-de-un-libro-intraducible#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Para Traductores\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/categorias\\\/para-traductores\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"El misterio de un libro intraducible\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"name\":\"Trusted Translations, Inc.\",\"description\":\"Leader in translation and interpretation services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"alternateName\":\"Trusted Translations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\",\"name\":\"Trusted Translations\",\"alternateName\":\"Trusted Translations, Inc.\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"contentUrl\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"width\":500,\"height\":196,\"caption\":\"Trusted Translations\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Trusted.Translations\",\"https:\\\/\\\/x.com\\\/TrustedT9ns\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/trusted-translations\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/fa7711d1d5a1a786b05cf22fb72afc46\",\"name\":\"clegnazzi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"clegnazzi\"},\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/author\\\/clegnazzi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El misterio de un libro intraducible - Trusted Translations","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-misterio-de-un-libro-intraducible","og_locale":"es_ES","og_type":"article","og_title":"El misterio de un libro intraducible - Trusted Translations","og_description":"En la Biblioteca Beinecke de Manuscritos y Libros Raros de la Universidad de Yale, en Estados Unidos, se encuentra un libro que nadie ha podido leer jam\u00e1s, escrito en un...","og_url":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-misterio-de-un-libro-intraducible","og_site_name":"Trusted Translations","article_publisher":"https:\/\/www.facebook.com\/Trusted.Translations","article_modified_time":"2023-01-26T16:06:29+00:00","og_image":[{"width":216,"height":94,"url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/06\/tt-logo-2-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@TrustedT9ns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-misterio-de-un-libro-intraducible#article","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-misterio-de-un-libro-intraducible"},"author":{"name":"clegnazzi","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/fa7711d1d5a1a786b05cf22fb72afc46"},"headline":"El misterio de un libro intraducible","datePublished":"2014-05-12T10:00:11+00:00","dateModified":"2023-01-26T16:06:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-misterio-de-un-libro-intraducible"},"wordCount":572,"commentCount":0,"publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"keywords":["c\u00f3digo","comunicaci\u00f3n","idioma","textos"],"articleSection":["Para Traductores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/el-misterio-de-un-libro-intraducible#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-misterio-de-un-libro-intraducible","url":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-misterio-de-un-libro-intraducible","name":"El misterio de un libro intraducible - Trusted Translations","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-misterio-de-un-libro-intraducible#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/el-misterio-de-un-libro-intraducible"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-misterio-de-un-libro-intraducible#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trustedtranslations.com\/es"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.trustedtranslations.com\/es\/blog"},{"@type":"ListItem","position":3,"name":"Para Traductores","item":"https:\/\/www.trustedtranslations.com\/es\/blog\/categorias\/para-traductores"},{"@type":"ListItem","position":4,"name":"El misterio de un libro intraducible"}]},{"@type":"WebSite","@id":"https:\/\/www.trustedtranslations.com\/es\/#website","url":"https:\/\/www.trustedtranslations.com\/es\/","name":"Trusted Translations, Inc.","description":"Leader in translation and interpretation services.","publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"alternateName":"Trusted Translations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trustedtranslations.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.trustedtranslations.com\/es\/#organization","name":"Trusted Translations","alternateName":"Trusted Translations, Inc.","url":"https:\/\/www.trustedtranslations.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","contentUrl":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","width":500,"height":196,"caption":"Trusted Translations"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Trusted.Translations","https:\/\/x.com\/TrustedT9ns","https:\/\/www.linkedin.com\/company\/trusted-translations"]},{"@type":"Person","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/fa7711d1d5a1a786b05cf22fb72afc46","name":"clegnazzi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"clegnazzi"},"url":"https:\/\/www.trustedtranslations.com\/es\/author\/clegnazzi"}]}},"toolset-meta":{"cpt-for-blogs":{"revisor":{"type":"textfield","raw":""},"revisor-image":{"type":"image","raw":"","attachment_id":null},"revisor-description":{"type":"textfield","raw":""},"revisor-link":{"type":"url","raw":""}}},"_links":{"self":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/114396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/comments?post=114396"}],"version-history":[{"count":0,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/114396\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/media?parent=114396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/categories?post=114396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/tags?post=114396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}