{"id":114444,"date":"2014-03-18T16:10:47","date_gmt":"2014-03-18T16:10:47","guid":{"rendered":"https:\/\/www.trustedtranslations.com\/?p=114444"},"modified":"2023-01-26T13:07:05","modified_gmt":"2023-01-26T16:07:05","slug":"errores-atomicos","status":"publish","type":"blog","link":"https:\/\/www.trustedtranslations.com\/es\/blog\/errores-atomicos","title":{"rendered":"Errores at\u00f3micos"},"content":{"rendered":"<p>Los traductores y las agencias de traducci\u00f3n nos topamos constantemente con traducciones err\u00f3neas o sin sentido, y en muchos casos (como las que publicamos en un <a href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/errores-de-pelicula\" target=\"_blank\" rel=\"noopener\">post<\/a> de hace algunas semanas en el que cit\u00e1bamos algunos ejemplos extra\u00eddos del mundo del cine) resultan graciosas. Pero el traducir es una labor esencial para el com\u00fan entendimiento entre las personas, y si uno no entiende algo en una pel\u00edcula o en un libro como mucho se perder\u00e1 algo del sentido, pero como no solo de pel\u00edculas vive el hombre, existe un sinf\u00edn de otras situaciones en las que la palabra debe ser siempre la precisa.<\/p>\n<p>Entre estas situaciones se encuentra el \u00e1mbito de las relaciones internacionales, donde la tarea de los int\u00e9rpretes es fundamental, dado que es justamente en este \u00e1mbito en el que constantemente est\u00e1n encontr\u00e1ndose (y a veces, demasiadas veces, enfrent\u00e1ndose) individuos o grupos que no pueden entenderse si no es a trav\u00e9s de un traductor o int\u00e9rprete. Ya vimos en otro <a href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/hiroshima-error-de-traduccion\" target=\"_blank\" rel=\"noopener\">post<\/a> de este blog que es probable que el bombardeo de Hiroshima haya sido causado por un error de traducci\u00f3n de la palabra <i>mokusatsu<\/i>, traducida por los int\u00e9rpretes estadounidenses en el sentido de que los japoneses estaban \u201cignorando\u201d su ultim\u00e1tum, en lugar del sentido que le habr\u00edan querido dar los japoneses, utilizando la palabra con la idea de que se \u201cabsten\u00edan de responder\u201d al ultim\u00e1tum. Esta mala traducci\u00f3n hizo parecer que Jap\u00f3n tomaba una postura desafiante ante la amenaza, y todos sabemos el desastroso resultado que eso tuvo.<\/p>\n<p>Otro caso similar, que tambi\u00e9n involucra a los Estados Unidos y al armamento nuclear, se dio algunos a\u00f1os m\u00e1s tarde. En un discurso dado en pleno auge de la Guerra Fr\u00eda, Nikita Khrushchev, en aquel entonces Primer Ministro de la Uni\u00f3n Sovi\u00e9tica, pronunci\u00f3\u00a0 una frase que fue retomada por los medios occidentales como: \u201clos vamos a enterrar\u201d. Teniendo en cuenta el tenso contexto pol\u00edtico y la creciente carrera armamentista entre los Estados Unidos y la Uni\u00f3n Sovi\u00e9tica, la noticia de que el primer ministro sovi\u00e9tico le dijera al mundo capitalista que lo enterrar\u00eda gener\u00f3 m\u00e1s que una preocupaci\u00f3n, al ser interpretada como una amenaza directa de un ataque nuclear. Naturalmente esto no hizo m\u00e1s que aumentar la tensi\u00f3n entre los dos bloques y posiblemente prolong\u00f3 el conflicto. Pero en realidad, se dice que lo que Khrushchev dijo fue algo m\u00e1s parecido a: \u201cviviremos para verlos enterrados\u201d, que es una expresi\u00f3n rusa com\u00fan que se usa en el sentido de \u201cviviremos m\u00e1s que ustedes\u201d, es decir, no se habr\u00eda tratado en realidad de una amenaza de ataque, sino m\u00e1s bien de una declaraci\u00f3n de superioridad.<\/p>\n<p>Vemos en estos ejemplos una vez m\u00e1s el enorme poder de la palabra, y la enorme responsabilidad que recae en ciertas ocasiones sobre los hombros de los traductores e int\u00e9rpretes, ya que el peque\u00f1o error de un hombre puede resultar en un gran error para la humanidad.<\/p>\n","protected":false},"excerpt":{"rendered":"Los traductores y las agencias de traducci\u00f3n nos topamos constantemente con traducciones err\u00f3neas o sin sentido, y en muchos casos (como las que publicamos en un post de hace algunas\u2026\n","protected":false},"author":63,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8893],"tags":[9389,9896,8506,9895,9837],"class_list":["post-114444","blog","type-blog","status-publish","format-standard","hentry","category-para-traductores","tag-error-de-traduccion","tag-hiroshima","tag-interpretes","tag-relaciones-internacionales","tag-ruso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Errores at\u00f3micos - Trusted Translations<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/errores-atomicos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Errores at\u00f3micos - Trusted Translations\" \/>\n<meta property=\"og:description\" content=\"Los traductores y las agencias de traducci\u00f3n nos topamos constantemente con traducciones err\u00f3neas o sin sentido, y en muchos casos (como las que publicamos en un post de hace algunas...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trustedtranslations.com\/es\/blog\/errores-atomicos\" \/>\n<meta property=\"og:site_name\" content=\"Trusted Translations\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Trusted.Translations\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-26T16:07:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/06\/tt-logo-2-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"216\" \/>\n\t<meta property=\"og:image:height\" content=\"94\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TrustedT9ns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/errores-atomicos#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/errores-atomicos\"},\"author\":{\"name\":\"agustinp\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/9e769f421341a589be2723d2d0565f73\"},\"headline\":\"Errores at\u00f3micos\",\"datePublished\":\"2014-03-18T16:10:47+00:00\",\"dateModified\":\"2023-01-26T16:07:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/errores-atomicos\"},\"wordCount\":531,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"keywords\":[\"error de traducci\u00f3n\",\"hiroshima\",\"interpr\u00e8tes\",\"relaciones internacionales\",\"ruso\"],\"articleSection\":[\"Para Traductores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/errores-atomicos#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/errores-atomicos\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/errores-atomicos\",\"name\":\"Errores at\u00f3micos - Trusted Translations\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/errores-atomicos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/errores-atomicos\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/errores-atomicos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Para Traductores\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/categorias\\\/para-traductores\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Errores at\u00f3micos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"name\":\"Trusted Translations, Inc.\",\"description\":\"Leader in translation and interpretation services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"alternateName\":\"Trusted Translations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\",\"name\":\"Trusted Translations\",\"alternateName\":\"Trusted Translations, Inc.\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"contentUrl\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"width\":500,\"height\":196,\"caption\":\"Trusted Translations\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Trusted.Translations\",\"https:\\\/\\\/x.com\\\/TrustedT9ns\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/trusted-translations\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/9e769f421341a589be2723d2d0565f73\",\"name\":\"agustinp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"agustinp\"},\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/author\\\/agustinp\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Errores at\u00f3micos - Trusted Translations","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trustedtranslations.com\/es\/blog\/errores-atomicos","og_locale":"es_ES","og_type":"article","og_title":"Errores at\u00f3micos - Trusted Translations","og_description":"Los traductores y las agencias de traducci\u00f3n nos topamos constantemente con traducciones err\u00f3neas o sin sentido, y en muchos casos (como las que publicamos en un post de hace algunas...","og_url":"https:\/\/www.trustedtranslations.com\/es\/blog\/errores-atomicos","og_site_name":"Trusted Translations","article_publisher":"https:\/\/www.facebook.com\/Trusted.Translations","article_modified_time":"2023-01-26T16:07:05+00:00","og_image":[{"width":216,"height":94,"url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/06\/tt-logo-2-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@TrustedT9ns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/errores-atomicos#article","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/errores-atomicos"},"author":{"name":"agustinp","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/9e769f421341a589be2723d2d0565f73"},"headline":"Errores at\u00f3micos","datePublished":"2014-03-18T16:10:47+00:00","dateModified":"2023-01-26T16:07:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/errores-atomicos"},"wordCount":531,"commentCount":0,"publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"keywords":["error de traducci\u00f3n","hiroshima","interpr\u00e8tes","relaciones internacionales","ruso"],"articleSection":["Para Traductores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/errores-atomicos#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/errores-atomicos","url":"https:\/\/www.trustedtranslations.com\/es\/blog\/errores-atomicos","name":"Errores at\u00f3micos - Trusted Translations","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/errores-atomicos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/errores-atomicos"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/errores-atomicos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trustedtranslations.com\/es"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.trustedtranslations.com\/es\/blog"},{"@type":"ListItem","position":3,"name":"Para Traductores","item":"https:\/\/www.trustedtranslations.com\/es\/blog\/categorias\/para-traductores"},{"@type":"ListItem","position":4,"name":"Errores at\u00f3micos"}]},{"@type":"WebSite","@id":"https:\/\/www.trustedtranslations.com\/es\/#website","url":"https:\/\/www.trustedtranslations.com\/es\/","name":"Trusted Translations, Inc.","description":"Leader in translation and interpretation services.","publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"alternateName":"Trusted Translations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trustedtranslations.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.trustedtranslations.com\/es\/#organization","name":"Trusted Translations","alternateName":"Trusted Translations, Inc.","url":"https:\/\/www.trustedtranslations.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","contentUrl":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","width":500,"height":196,"caption":"Trusted Translations"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Trusted.Translations","https:\/\/x.com\/TrustedT9ns","https:\/\/www.linkedin.com\/company\/trusted-translations"]},{"@type":"Person","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/9e769f421341a589be2723d2d0565f73","name":"agustinp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"agustinp"},"url":"https:\/\/www.trustedtranslations.com\/es\/author\/agustinp"}]}},"toolset-meta":{"cpt-for-blogs":{"revisor":{"type":"textfield","raw":""},"revisor-image":{"type":"image","raw":"","attachment_id":null},"revisor-description":{"type":"textfield","raw":""},"revisor-link":{"type":"url","raw":""}}},"_links":{"self":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/114444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/comments?post=114444"}],"version-history":[{"count":0,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/114444\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/media?parent=114444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/categories?post=114444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/tags?post=114444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}