{"id":115284,"date":"2011-08-08T11:57:52","date_gmt":"2011-08-08T11:57:52","guid":{"rendered":"https:\/\/www.trustedtranslations.com\/?p=115284"},"modified":"2022-02-10T18:24:06","modified_gmt":"2022-02-10T18:24:06","slug":"algunas-estadisticas-acerca-de-la-educacion-por-internet","status":"publish","type":"blog","link":"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet","title":{"rendered":"Algunas estad\u00edsticas acerca de la Educaci\u00f3n por Internet"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2011\/08\/Picture-3.png\" \/>En posts anteriores mencion\u00e9 el estudio de idiomas a trav\u00e9s de Internet. Pensaba publicar algo acerca del mismo tema; pero, investigando para mi pr\u00f3xima nota, encontr\u00e9 esta informaci\u00f3n que no me dej\u00f3 indiferente.<br \/>El poder de la ense\u00f1anza pas\u00f3 de estar en manos de las instituciones educativas a la de los estudiantes. En estos tiempos la educaci\u00f3n est\u00e1 m\u00e1s accesible que nunca en la historia de la humanidad. Todo gracias a Internet.<br \/>Volviendo algunos a\u00f1os hacia atr\u00e1s,<br \/>&#8211; En los a\u00f1os 70 la Universidad Abierta de Inglaterra abre sus puertas al ingreso por medio de una p\u00f3liza de admisi\u00f3n. Se inscriben 25,000 estudiantes.<br \/>&#8211; En los 90s, la Universidad de Phoenix, en Estados Unidos., lanza un sistema privado de ense\u00f1anza online. Se inscriben 12 estudiantes.<br \/>&#8211; En 1993, bajo el mando de William Graziadei, se crea el sistema de e-learning: b\u00e1sicamente una plataforma educativa con soporte acad\u00e9mico y tutores online. El objetivo es crear un sistema, no presencial que permitiera a los estudiantes administrar su tiempo para estudiar desde cualquier lugar. Que sea f\u00e1cil de usar, replicable, escalable y accesible para todo aquel que quiera aprender. Lo \u00fanico indispensable: una computadora y conexi\u00f3n a Internet.<br \/>&#8211; En 1999, el t\u00e9rmino e-learning se empieza a mencionar en seminarios de Educaci\u00f3n.<br \/>&#8211; En 2004, Salman Khan graba videos instructivos de matem\u00e1ticas en You Tube con la intenci\u00f3n de ayudar a su sobrina en sus tareas escolares. La popularidad que le dieron estos videos lo lleva a fundar la Khan Academy. Una organizaci\u00f3n educacional gratuita y sin fines de lucro.<br \/>La Educaci\u00f3n Online es una Industria de 34 billones de d\u00f3lares. Actualmente:<br \/>&#8211; La Universidad abierta tiene 10.000 estudiantes. La mayor\u00eda de sus cursos son online. Con 250.000 estudiantes, es la Universidad m\u00e1s concurrida de Inglaterra.<br \/>&#8211; Salman Khan, de la Khan Academy lleva grabados 2.100 videos educativos vistos 41 millones de veces. Para hacer una comparaci\u00f3n, es el n\u00famero de visitas que recibir\u00edan si cada estudiante de\u00a0 Estados Unidos lo viera una vez.<br \/>Internet est\u00e1 cambiando el modo de estudiar y aprender.<br \/>Desde instituciones de educaci\u00f3n tradicional hasta organizaciones de e-learning, tanto pagas como gratuitas ofrecen todo un nuevo sistema de aprendizaje.<br \/>Hoy en d\u00eda hay 25.000 cursos online ofrecidos en Estados Unidos.<br \/>Actualmente hay 3 millones de estudiantes solamente en Estados Unidos. que solo lo hacen por Internet. Casi la mitad de los estudiantes online tiene un promedio de 26 a\u00f1os o m\u00e1s edad. Cada vez hay m\u00e1s adeptos de edades m\u00e1s avanzadas.<br \/>El uso de la educaci\u00f3n online est\u00e1 creciendo\u2026\u00a1y no para!. En Estados Unidos, el 75% de las instituciones de ense\u00f1anza p\u00fablica tienen educaci\u00f3n online en sus programas anuales. Para el a\u00f1o 2019 se calcula que el 50% de todos los cursos ense\u00f1ados ser\u00e1n entregados online, y muchos de estos ser\u00e1n gratuitos.<br \/>Itunes ofrece m\u00e1s de 350.000 lecciones escolares y videos de m\u00e1s de 800 universidades, incluyendo Stanford, Yale y Oxford, todo en forma gratuita. El a\u00f1o pasado, The London School of Business and Finance lanz\u00f3 al Mercado \u201cThe Global M.B.A\u00bb entregado en su totalidad a trav\u00e9s de APPs* de Facebook.<br \/>Bill Gates hizo una donaci\u00f3n de $2 millones de d\u00f3lares para el desarrollo de apps de Facebook, con la finalidad de captar la atenci\u00f3n de nuevos estudiantes y fomentar la educaci\u00f3n.<br \/>El modelo antiguo hace que en la mayor\u00eda de los pa\u00edses la educaci\u00f3n siga siendo muy costosa, pero hoy en d\u00eda dej\u00f3 de ser una opci\u00f3n para pocos. Cualquier persona con una conexi\u00f3n a internet puede aprender, sean cuales sean sus intereses. Nunca la educaci\u00f3n fue tan comprensible ni democr\u00e1tica, y todo indica que con el tiempo, no habr\u00e1 m\u00e1s que mejorarla.<\/p>\n<p>*App: Es un programa que se instala en un dispositivo m\u00f3vil -ya sea tel\u00e9fono o tableta.Las aplicaciones proveen acceso instant\u00e1neo a un contenido sin tener que buscarlo en Internet y, una vez instaladas, generalmente se puede acceder a ellas sin necesidad de una conexi\u00f3n a la Red.<\/p>\n","protected":false},"excerpt":{"rendered":"En posts anteriores mencion\u00e9 el estudio de idiomas a trav\u00e9s de Internet. Pensaba publicar algo acerca del mismo tema; pero, investigando para mi pr\u00f3xima nota, encontr\u00e9 esta informaci\u00f3n que no\u2026\n","protected":false},"author":96,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8893],"tags":[10638,8880,10636,8147,10628,10634,10632,10630,10629,10627,9465,10637,10635,10633,10631],"class_list":["post-115284","blog","type-blog","status-publish","format-standard","hentry","category-para-traductores","tag-app-de-facebook","tag-aprender-idiomas","tag-aprender-por-internet","tag-e-learning","tag-estadisticas","tag-estudiar-gratis","tag-estudiar-online","tag-industria-del-aprendizaje-online","tag-itunes","tag-lecciones-escolares-online","tag-oxford","tag-stanford","tag-the-global-m-b-a","tag-the-london-school-of-business","tag-yale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Algunas estad\u00edsticas acerca de la Educaci\u00f3n por Internet - Trusted Translations<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Algunas estad\u00edsticas acerca de la Educaci\u00f3n por Internet - Trusted Translations\" \/>\n<meta property=\"og:description\" content=\"En posts anteriores mencion\u00e9 el estudio de idiomas a trav\u00e9s de Internet. Pensaba publicar algo acerca del mismo tema; pero, investigando para mi pr\u00f3xima nota, encontr\u00e9 esta informaci\u00f3n que no...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet\" \/>\n<meta property=\"og:site_name\" content=\"Trusted Translations\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Trusted.Translations\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-10T18:24:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2011\/08\/Picture-3.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TrustedT9ns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/algunas-estadisticas-acerca-de-la-educacion-por-internet#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/algunas-estadisticas-acerca-de-la-educacion-por-internet\"},\"author\":{\"name\":\"florencialf\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/341e65060741883e2594be02b2b57c7a\"},\"headline\":\"Algunas estad\u00edsticas acerca de la Educaci\u00f3n por Internet\",\"datePublished\":\"2011-08-08T11:57:52+00:00\",\"dateModified\":\"2022-02-10T18:24:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/algunas-estadisticas-acerca-de-la-educacion-por-internet\"},\"wordCount\":709,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/algunas-estadisticas-acerca-de-la-educacion-por-internet#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/Picture-3.png\",\"keywords\":[\"app de facebook\",\"aprender idiomas\",\"aprender por internet\",\"e-learning\",\"estad\u00edsticas\",\"estudiar gratis\",\"estudiar online\",\"industria del aprendizaje online\",\"itunes\",\"lecciones escolares online\",\"Oxford\",\"Stanford\",\"The Global M.B.A.\",\"The London School of Business\",\"Yale\"],\"articleSection\":[\"Para Traductores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/algunas-estadisticas-acerca-de-la-educacion-por-internet#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/algunas-estadisticas-acerca-de-la-educacion-por-internet\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/algunas-estadisticas-acerca-de-la-educacion-por-internet\",\"name\":\"Algunas estad\u00edsticas acerca de la Educaci\u00f3n por Internet - Trusted Translations\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/algunas-estadisticas-acerca-de-la-educacion-por-internet#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/algunas-estadisticas-acerca-de-la-educacion-por-internet#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/Picture-3.png\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/algunas-estadisticas-acerca-de-la-educacion-por-internet#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/algunas-estadisticas-acerca-de-la-educacion-por-internet\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/algunas-estadisticas-acerca-de-la-educacion-por-internet#primaryimage\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/Picture-3.png\",\"contentUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/Picture-3.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/algunas-estadisticas-acerca-de-la-educacion-por-internet#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Para Traductores\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/categorias\\\/para-traductores\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Algunas estad\u00edsticas acerca de la Educaci\u00f3n por Internet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"name\":\"Trusted Translations, Inc.\",\"description\":\"Leader in translation and interpretation services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"alternateName\":\"Trusted Translations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\",\"name\":\"Trusted Translations\",\"alternateName\":\"Trusted Translations, Inc.\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"contentUrl\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"width\":500,\"height\":196,\"caption\":\"Trusted Translations\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Trusted.Translations\",\"https:\\\/\\\/x.com\\\/TrustedT9ns\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/trusted-translations\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/341e65060741883e2594be02b2b57c7a\",\"name\":\"florencialf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"florencialf\"},\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/author\\\/florencialf\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Algunas estad\u00edsticas acerca de la Educaci\u00f3n por Internet - Trusted Translations","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet","og_locale":"es_ES","og_type":"article","og_title":"Algunas estad\u00edsticas acerca de la Educaci\u00f3n por Internet - Trusted Translations","og_description":"En posts anteriores mencion\u00e9 el estudio de idiomas a trav\u00e9s de Internet. Pensaba publicar algo acerca del mismo tema; pero, investigando para mi pr\u00f3xima nota, encontr\u00e9 esta informaci\u00f3n que no...","og_url":"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet","og_site_name":"Trusted Translations","article_publisher":"https:\/\/www.facebook.com\/Trusted.Translations","article_modified_time":"2022-02-10T18:24:06+00:00","og_image":[{"url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2011\/08\/Picture-3.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@TrustedT9ns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet#article","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet"},"author":{"name":"florencialf","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/341e65060741883e2594be02b2b57c7a"},"headline":"Algunas estad\u00edsticas acerca de la Educaci\u00f3n por Internet","datePublished":"2011-08-08T11:57:52+00:00","dateModified":"2022-02-10T18:24:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet"},"wordCount":709,"commentCount":0,"publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet#primaryimage"},"thumbnailUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2011\/08\/Picture-3.png","keywords":["app de facebook","aprender idiomas","aprender por internet","e-learning","estad\u00edsticas","estudiar gratis","estudiar online","industria del aprendizaje online","itunes","lecciones escolares online","Oxford","Stanford","The Global M.B.A.","The London School of Business","Yale"],"articleSection":["Para Traductores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet","url":"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet","name":"Algunas estad\u00edsticas acerca de la Educaci\u00f3n por Internet - Trusted Translations","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet#primaryimage"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet#primaryimage"},"thumbnailUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2011\/08\/Picture-3.png","breadcrumb":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet#primaryimage","url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2011\/08\/Picture-3.png","contentUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2011\/08\/Picture-3.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/algunas-estadisticas-acerca-de-la-educacion-por-internet#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trustedtranslations.com\/es"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.trustedtranslations.com\/es\/blog"},{"@type":"ListItem","position":3,"name":"Para Traductores","item":"https:\/\/www.trustedtranslations.com\/es\/blog\/categorias\/para-traductores"},{"@type":"ListItem","position":4,"name":"Algunas estad\u00edsticas acerca de la Educaci\u00f3n por Internet"}]},{"@type":"WebSite","@id":"https:\/\/www.trustedtranslations.com\/es\/#website","url":"https:\/\/www.trustedtranslations.com\/es\/","name":"Trusted Translations, Inc.","description":"Leader in translation and interpretation services.","publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"alternateName":"Trusted Translations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trustedtranslations.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.trustedtranslations.com\/es\/#organization","name":"Trusted Translations","alternateName":"Trusted Translations, Inc.","url":"https:\/\/www.trustedtranslations.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","contentUrl":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","width":500,"height":196,"caption":"Trusted Translations"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Trusted.Translations","https:\/\/x.com\/TrustedT9ns","https:\/\/www.linkedin.com\/company\/trusted-translations"]},{"@type":"Person","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/341e65060741883e2594be02b2b57c7a","name":"florencialf","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"florencialf"},"url":"https:\/\/www.trustedtranslations.com\/es\/author\/florencialf"}]}},"toolset-meta":{"cpt-for-blogs":{"revisor":{"type":"textfield","raw":""},"revisor-image":{"type":"image","raw":"","attachment_id":null},"revisor-description":{"type":"textfield","raw":""},"revisor-link":{"type":"url","raw":""}}},"_links":{"self":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/115284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/users\/96"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/comments?post=115284"}],"version-history":[{"count":0,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/115284\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/media?parent=115284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/categories?post=115284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/tags?post=115284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}