{"id":116145,"date":"2009-01-30T11:29:07","date_gmt":"2009-01-30T11:29:07","guid":{"rendered":"https:\/\/www.trustedtranslations.com\/?p=116145"},"modified":"2022-02-10T18:52:24","modified_gmt":"2022-02-10T18:52:24","slug":"el-presidente-obama-y-el-poder-de-las-palabras","status":"publish","type":"blog","link":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-presidente-obama-y-el-poder-de-las-palabras","title":{"rendered":"El Presidente Obama y el poder de las palabras"},"content":{"rendered":"<p>El martes a la noche, en alg\u00fan momento durante mi marat\u00f3n televisiva por la CNN y la BBC de las actividades inaugurales y el evidente cenit de la Obamaman\u00eda, uno de los muchos analistas\/comentaristas pol\u00edticos se refiri\u00f3 al \u201cpoder de las palabras\u201d. A pesar de que he le\u00eddo uno de los libros de Barack y visto docenas de debates y discursos, sumamente enriquecedores por el uso del idioma del Presidente, el reconocimiento aparentemente an\u00f3nimo, indiferente y casi clich\u00e9 de las habilidades de oratoria del Presidente N.\u00ba 44 y del poder de las palabras realmente caus\u00f3 un gran impacto en m\u00ed. M\u00e1s que las propuestas de medidas pol\u00edticas, m\u00e1s que su temprana oposici\u00f3n a la invasi\u00f3n de Irak, incluso m\u00e1s que Internet, la herramienta m\u00e1s poderosa que Obama ha utilizado para saltar al pin\u00e1culo del poder pol\u00edtico, sin mencionar el cultural, ha sido el idioma, tanto escrito como oral.<\/p>\n<p>Podemos recordar f\u00e1cilmente su pasado como organizador comunitario o como Presidente de la Revista Jur\u00eddica de Harvard o, incluso, podemos apreciar la importancia crucial del idioma en el vertiginoso ascenso al poder de Barack Obama. Public\u00f3 su primer libro en 1995, pero tanto \u00e9l como el libro s\u00f3lo cobraron popularidad nacional despu\u00e9s de la t\u00f3nica de su discurso en la Convenci\u00f3n Nacional Dem\u00f3crata de 2004. En las primarias dem\u00f3cratas de 2008, Hillary se lament\u00f3 constantemente por la oratoria desplegada en la t\u00f3nica del discurso que transform\u00f3 inmerecidamente a un joven e inexperto legislador estatal en una celebridad y potencial candidato presidencial. El segundo libro se public\u00f3 en 2006 y r\u00e1pidamente se convirti\u00f3 en un bestseller. La impresionante recepci\u00f3n favorable del libro evidentemente alent\u00f3 a Obama a postularse para la Presidencia de los Estados Unidos.<\/p>\n<p>El poderoso uso del idioma de Obama de evidenci\u00f3 peri\u00f3dicamente, de concentraci\u00f3n pol\u00edtica en concentraci\u00f3n pol\u00edtica, de discurso en discurso, de debate en debate (28 en total), a lo largo de la campa\u00f1a presidencial m\u00e1s larga de la historia de los Estados Unidos. Hace casi un a\u00f1o, en febrero de 2008, el <em>Wall Street Journal <\/em>public\u00f3 un art\u00edculo con el t\u00edtulo que hemos utilizado aqu\u00ed. En el mismo mes, mientras Barack consolidaba su designaci\u00f3n en contra de Hillary en las primarias dem\u00f3cratas, el <em>Washington Post<\/em> public\u00f3 un art\u00edculo titulado \u201cC\u00f3mo encontrar la fortaleza pol\u00edtica en el poder de las palabras\u201d. Esto ocurri\u00f3 antes de su \u201cDiscurso para la carrera presidencial\u201d en Filadelfia. Esto ocurri\u00f3 antes de que hablara ante 200.000 personas en Berl\u00edn. Esto ocurri\u00f3 antes de que aceptara la designaci\u00f3n en un estadio colmado en Denver, antes de que triunfara en los debates contra su oponente republicano en las 3 ocasiones, mucho antes de su discurso de victoria en Grant Park, y casi un a\u00f1o antes de su discurso en la semana inaugural que ha suscitado tanto inter\u00e9s y la frecuente adulaci\u00f3n de la oratoria del Presidente Obama en estos d\u00edas.<\/p>\n<p>De las muchas lecciones que pudimos aprender, o recordar, de la elecci\u00f3n presidencial de 2008, la m\u00e1s importante, a mi criterio, ha sido el <strong>poder de las palabras<\/strong>. S\u00ed, las palabras son extremadamente poderosas. Quiz\u00e1s no muevan monta\u00f1as, pero seguramente pueden conducir a la Casa Blanca. Y esta no es una lecci\u00f3n s\u00f3lo para los que tienen ambiciones pol\u00edticas. Las palabras son importantes, para todos. Respecto de la oratoria de Obama en tanto \u201cestudio de compromiso positivo\u201d, un blogger concluy\u00f3: \u201cEstoy reescribiendo las palabras de mi vida para tomar las riendas de mi propia carrera hacia una vida m\u00e1s satisfactoria\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"El martes a la noche, en alg\u00fan momento durante mi marat\u00f3n televisiva por la CNN y la BBC de las actividades inaugurales y el evidente cenit de la Obamaman\u00eda, uno\u2026\n","protected":false},"author":101,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8932,8794,8893],"tags":[9419,12162,12161,11902,12131,12164,12163,12154,9320,12153,12160],"class_list":["post-116145","blog","type-blog","status-publish","format-standard","hentry","category-acerca-de-trusted-translations","category-para-compradores-de-traduccion","category-para-traductores","tag-campana-presidencial","tag-candidato-presidencial","tag-carrera-presidencial","tag-discursos-politicos","tag-discursos-presidenciales","tag-elecciones-presidenciales","tag-obamamania","tag-poder-de-las-palabras","tag-politica","tag-presidente-de-los-estados-unidos","tag-uso-del-idioma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Presidente Obama y el poder de las palabras - Trusted Translations<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/el-presidente-obama-y-el-poder-de-las-palabras\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Presidente Obama y el poder de las palabras - Trusted Translations\" \/>\n<meta property=\"og:description\" content=\"El martes a la noche, en alg\u00fan momento durante mi marat\u00f3n televisiva por la CNN y la BBC de las actividades inaugurales y el evidente cenit de la Obamaman\u00eda, uno...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trustedtranslations.com\/es\/blog\/el-presidente-obama-y-el-poder-de-las-palabras\" \/>\n<meta property=\"og:site_name\" content=\"Trusted Translations\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Trusted.Translations\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-10T18:52:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/06\/tt-logo-2-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"216\" \/>\n\t<meta property=\"og:image:height\" content=\"94\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TrustedT9ns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-presidente-obama-y-el-poder-de-las-palabras#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-presidente-obama-y-el-poder-de-las-palabras\"},\"author\":{\"name\":\"amelia\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/62defe2697007232485f33d6355d66b5\"},\"headline\":\"El Presidente Obama y el poder de las palabras\",\"datePublished\":\"2009-01-30T11:29:07+00:00\",\"dateModified\":\"2022-02-10T18:52:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-presidente-obama-y-el-poder-de-las-palabras\"},\"wordCount\":629,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"keywords\":[\"campa\u00f1a presidencial\",\"candidato presidencial\",\"carrera presidencial\",\"discursos pol\u00edticos\",\"discursos presidenciales\",\"elecciones presidenciales\",\"Obamaman\u00eda\",\"poder de las palabras\",\"pol\u00edtica\",\"Presidente de los Estados Unidos\",\"uso del idioma\"],\"articleSection\":[\"Acerca de Trusted Translations\",\"Para Compradores de Traducci\u00f3n\",\"Para Traductores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-presidente-obama-y-el-poder-de-las-palabras#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-presidente-obama-y-el-poder-de-las-palabras\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-presidente-obama-y-el-poder-de-las-palabras\",\"name\":\"El Presidente Obama y el poder de las palabras - Trusted Translations\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-presidente-obama-y-el-poder-de-las-palabras#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-presidente-obama-y-el-poder-de-las-palabras\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/el-presidente-obama-y-el-poder-de-las-palabras#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Acerca de Trusted Translations\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/categorias\\\/acerca-de-trusted-translations\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"El Presidente Obama y el poder de las palabras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"name\":\"Trusted Translations, Inc.\",\"description\":\"Leader in translation and interpretation services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"alternateName\":\"Trusted Translations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\",\"name\":\"Trusted Translations\",\"alternateName\":\"Trusted Translations, Inc.\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"contentUrl\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"width\":500,\"height\":196,\"caption\":\"Trusted Translations\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Trusted.Translations\",\"https:\\\/\\\/x.com\\\/TrustedT9ns\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/trusted-translations\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/62defe2697007232485f33d6355d66b5\",\"name\":\"amelia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"amelia\"},\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/author\\\/amelia\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Presidente Obama y el poder de las palabras - Trusted Translations","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-presidente-obama-y-el-poder-de-las-palabras","og_locale":"es_ES","og_type":"article","og_title":"El Presidente Obama y el poder de las palabras - Trusted Translations","og_description":"El martes a la noche, en alg\u00fan momento durante mi marat\u00f3n televisiva por la CNN y la BBC de las actividades inaugurales y el evidente cenit de la Obamaman\u00eda, uno...","og_url":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-presidente-obama-y-el-poder-de-las-palabras","og_site_name":"Trusted Translations","article_publisher":"https:\/\/www.facebook.com\/Trusted.Translations","article_modified_time":"2022-02-10T18:52:24+00:00","og_image":[{"width":216,"height":94,"url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/06\/tt-logo-2-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@TrustedT9ns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-presidente-obama-y-el-poder-de-las-palabras#article","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-presidente-obama-y-el-poder-de-las-palabras"},"author":{"name":"amelia","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/62defe2697007232485f33d6355d66b5"},"headline":"El Presidente Obama y el poder de las palabras","datePublished":"2009-01-30T11:29:07+00:00","dateModified":"2022-02-10T18:52:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-presidente-obama-y-el-poder-de-las-palabras"},"wordCount":629,"commentCount":0,"publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"keywords":["campa\u00f1a presidencial","candidato presidencial","carrera presidencial","discursos pol\u00edticos","discursos presidenciales","elecciones presidenciales","Obamaman\u00eda","poder de las palabras","pol\u00edtica","Presidente de los Estados Unidos","uso del idioma"],"articleSection":["Acerca de Trusted Translations","Para Compradores de Traducci\u00f3n","Para Traductores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/el-presidente-obama-y-el-poder-de-las-palabras#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-presidente-obama-y-el-poder-de-las-palabras","url":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-presidente-obama-y-el-poder-de-las-palabras","name":"El Presidente Obama y el poder de las palabras - Trusted Translations","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-presidente-obama-y-el-poder-de-las-palabras#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/el-presidente-obama-y-el-poder-de-las-palabras"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/el-presidente-obama-y-el-poder-de-las-palabras#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trustedtranslations.com\/es"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.trustedtranslations.com\/es\/blog"},{"@type":"ListItem","position":3,"name":"Acerca de Trusted Translations","item":"https:\/\/www.trustedtranslations.com\/es\/blog\/categorias\/acerca-de-trusted-translations"},{"@type":"ListItem","position":4,"name":"El Presidente Obama y el poder de las palabras"}]},{"@type":"WebSite","@id":"https:\/\/www.trustedtranslations.com\/es\/#website","url":"https:\/\/www.trustedtranslations.com\/es\/","name":"Trusted Translations, Inc.","description":"Leader in translation and interpretation services.","publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"alternateName":"Trusted Translations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trustedtranslations.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.trustedtranslations.com\/es\/#organization","name":"Trusted Translations","alternateName":"Trusted Translations, Inc.","url":"https:\/\/www.trustedtranslations.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","contentUrl":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","width":500,"height":196,"caption":"Trusted Translations"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Trusted.Translations","https:\/\/x.com\/TrustedT9ns","https:\/\/www.linkedin.com\/company\/trusted-translations"]},{"@type":"Person","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/62defe2697007232485f33d6355d66b5","name":"amelia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"amelia"},"url":"https:\/\/www.trustedtranslations.com\/es\/author\/amelia"}]}},"toolset-meta":{"cpt-for-blogs":{"revisor":{"type":"textfield","raw":""},"revisor-image":{"type":"image","raw":"","attachment_id":null},"revisor-description":{"type":"textfield","raw":""},"revisor-link":{"type":"url","raw":""}}},"_links":{"self":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/116145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/comments?post=116145"}],"version-history":[{"count":0,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/116145\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/media?parent=116145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/categories?post=116145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/tags?post=116145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}