{"id":157069,"date":"2022-08-24T15:55:16","date_gmt":"2022-08-24T15:55:16","guid":{"rendered":"https:\/\/www.trustedtranslations.com\/?post_type=blog&#038;p=157069"},"modified":"2023-01-26T12:37:36","modified_gmt":"2023-01-26T15:37:36","slug":"hablas-aranes","status":"publish","type":"blog","link":"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes","title":{"rendered":"\u00bfHablas aran\u00e9s?"},"content":{"rendered":"<p>Es muy probable que no hables aran\u00e9s. De hecho, es muy probable que nunca hayas o\u00eddo hablar del aran\u00e9s. Esta es la lengua que hablan los habitantes de Valle de Ar\u00e1n, en los Pirineos.<\/p>\n<p>La comarca de Valle de Ar\u00e1n, ubicada en la vertiente norte de los Pirineos, tiene una geograf\u00eda \u00fanica. Y, si bien la mayor parte de la vertiente norte se encuentra en Francia, este valle nevado y monta\u00f1oso pertenece a la comunidad aut\u00f3noma de Catalu\u00f1a, en Espa\u00f1a. En este valle remoto habitan alrededor de 10\u00a0000 personas.<\/p>\n<p>En una <a href=\"https:\/\/www.bbc.com\/travel\/article\/20220117-aranese-spains-little-known-language\" target=\"_blank\" rel=\"noopener\">nota reciente de la BBC<\/a>, Richard Collet echa un vistazo a la regi\u00f3n. Algunos residentes de Valle de Ar\u00e1n afirmaron, sin vacilar, que ellos se identifican ante todo como araneses. Valle de Ar\u00e1n cuenta con un mayor grado de autonom\u00eda desde 1991. En 2010, el aran\u00e9s fue reconocido como tercera <a href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/los-paises-con-mas-lenguas-oficiales\" target=\"_blank\" rel=\"noopener\">lengua oficial<\/a> de Catalu\u00f1a.<\/p>\n<h2><strong>La historia del aran\u00e9s<\/strong><\/h2>\n<p>El aran\u00e9s es uno de varios dialectos del <a href=\"https:\/\/en.wikipedia.org\/wiki\/Occitan_language\" target=\"_blank\" rel=\"noopener\">occitano<\/a>. Prevalente durante la Edad Media, esta <a href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/el-romance-detras-de-las-lenguas-romances\" target=\"_blank\" rel=\"noopener\">lengua romance<\/a> floreci\u00f3 en el sur de Francia, en M\u00f3naco y en distintas partes de Italia y Espa\u00f1a.<\/p>\n<p>El occitano se entend\u00eda en toda Europa y los trovadores lo usaban en sus canciones y poes\u00edas. Algunos notables hablantes del occitano fueron el Ricardo I de Inglaterra (Ricardo Coraz\u00f3n de Le\u00f3n) y su madre, Leonor de Aquitania.<\/p>\n<p>El occitano era una lengua de las clases cultas de Europa, pero, en sus regiones principales, era la lengua dominante. A diferencia de otras lenguas, el occitano fue, y sigue siendo, formado por distintos dialectos, carente de una lengua est\u00e1ndar.<\/p>\n<p>Con los a\u00f1os, los hablantes del occitano fueron cada vez menos, a medida que fue reemplazado por el franc\u00e9s, el espa\u00f1ol y otras lenguas. Todos los dialectos del occitano se consideran como <a href=\"\/es\/blog\/que-es-la-preservacion-de-las-lenguas-y-por-que-es-tan-importante\" target=\"_blank\" rel=\"noopener\">lenguas en peligro de extinci\u00f3n<\/a> hoy en d\u00eda. Otros nombres que ver\u00e1s para referirse al occitano, particularmente en la historia, incluyen el provenzal y el limos\u00edn.<\/p>\n<p>El catal\u00e1n es un pariente cercano del occitano. El aran\u00e9s forma parte del dialecto gasc\u00f3n del occitano y es la \u00fanica lengua occitana con estatus oficial.<\/p>\n<h2><strong>El aran\u00e9s hoy<\/strong><\/h2>\n<p>Las lenguas occitanas pueden estar en peligro de extinci\u00f3n, pero en Valle de Ar\u00e1n, el aran\u00e9s persiste. Desde que fue reconocido como lengua oficial, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Aranese_dialect\" target=\"_blank\" rel=\"noopener\">se ense\u00f1a en escuelas<\/a> y se usa en letreros dentro de la comarca.<\/p>\n<p>El estatus oficial le otorga cierto grado de protecci\u00f3n al aran\u00e9s. Los habitantes de Valle de Ar\u00e1n se aferran con orgullo a su herencia ling\u00fc\u00edstica y producen informaci\u00f3n, literatura y entretenimiento en su lengua madre.<\/p>\n<p>Algunos esparcen la lengua por todo el continente, como lo hicieron los trovadores de la Edad Media.<\/p>\n<p>Aunque fuera un lugar remoto, Valle de Ar\u00e1n siempre tuvo contacto con otras lenguas, principalmente a trav\u00e9s del comercio con Francia y Espa\u00f1a. El aislamiento no es la raz\u00f3n por la cual el aran\u00e9s ha sobrevivido.<\/p>\n<p>Los habitantes del valle siempre valoraron su autonom\u00eda. Si bien es parte de Espa\u00f1a, la comunidad breg\u00f3 y negoci\u00f3 durante siglos por conservar sus fueros. No es sorprendente que tambi\u00e9n se aferraran a su lengua.<\/p>\n<p>Alrededor del 40\u00a0% de los habitantes de Valle de Ar\u00e1n han logrado el triplete aran\u00e9s: hablan, leen y escriben en esta lengua. No parece un alto n\u00famero. Pero, vi\u00e9ndolos por separado, encontrar\u00e1s que casi el <a href=\"https:\/\/infogalactic.com\/info\/Aranese_dialect\" target=\"_blank\" rel=\"noopener\">90\u00a0%<\/a> entienden el aran\u00e9s y m\u00e1s del 60\u00a0% lo hablan.<\/p>\n<p>Mientras que el turismo y la inmigraci\u00f3n contrarrestan la expansi\u00f3n e influencia naturales del aran\u00e9s, la lengua permanece una parte de la cultura general.<\/p>\n<p>Muchos hablan aran\u00e9s en sus hogares, aunque usen el catal\u00e1n o el espa\u00f1ol para comunicarse con los que vienen de afuera. Hablar aran\u00e9s significa acceder a la cultura medieval que se conserva en los edificios y en las tradiciones del valle.<\/p>\n<p>Algunos temen que la influencia de turistas y la necesidad de comunicarse con ellos hace que el aran\u00e9s se acerque a la extinci\u00f3n. Otros creen que la lengua es mucho m\u00e1s resistente. Su estatus oficial significa que los ni\u00f1os aprenden la lengua en la escuela y esto en un paso importante para la conservaci\u00f3n del aran\u00e9s.<\/p>\n<p>Aquellos que viven en Valle de Ar\u00e1n reconocen la importancia del legado de su lengua. Muchos son multiling\u00fces y hablan tres o cuatro lenguas. El aran\u00e9s es la lengua del hogar, de la cultura y de la historia.<\/p>\n<p>Que el aran\u00e9s sobreviva o no recae sobre la voluntad colectiva y la memoria cultural. El estatus oficial tiene el poder de garantizar que la lengua no tendr\u00e1 una muerte prematura. Si uno observa su historia, parece poco probable que los residentes de Valle de Ar\u00e1n dejen morir su lengua sin intentar salvarla.<\/p>\n","protected":false},"excerpt":{"rendered":"Es muy probable que no hables aran\u00e9s. De hecho, es muy probable que nunca hayas o\u00eddo hablar del aran\u00e9s. Esta es la lengua que hablan los habitantes de Valle de\u2026\n","protected":false},"author":4,"featured_media":156520,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8800],"tags":[9784,8816,11728,14906],"class_list":["post-157069","blog","type-blog","status-publish","format-standard","has-post-thumbnail","hentry","category-lenguaje","tag-idioma-oficial","tag-lenguas-en-peligro-de-extincion","tag-lenguas-romance","tag-official-language"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfHablas aran\u00e9s? - Trusted Translations<\/title>\n<meta name=\"description\" content=\"Es poco probable que hables aran\u00e9s. Lee m\u00e1s para aprender sobre esta extra\u00f1a pero perseverante lengua de los Pirineos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfHablas aran\u00e9s? - Trusted Translations\" \/>\n<meta property=\"og:description\" content=\"Es poco probable que hables aran\u00e9s. Lee m\u00e1s para aprender sobre esta extra\u00f1a pero perseverante lengua de los Pirineos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes\" \/>\n<meta property=\"og:site_name\" content=\"Trusted Translations\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Trusted.Translations\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-26T15:37:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/08\/Aranese-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"679\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TrustedT9ns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/hablas-aranes#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/hablas-aranes\"},\"author\":{\"name\":\"Trusted Translations\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/75fa06fac744ed0db519464a2e6ad900\"},\"headline\":\"\u00bfHablas aran\u00e9s?\",\"datePublished\":\"2022-08-24T15:55:16+00:00\",\"dateModified\":\"2023-01-26T15:37:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/hablas-aranes\"},\"wordCount\":839,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/hablas-aranes#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Aranese-scaled.jpeg\",\"keywords\":[\"idioma oficial\",\"lenguas en peligro de extinci\u00f3n\",\"lenguas romance\",\"official language\"],\"articleSection\":[\"Lenguaje\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/hablas-aranes\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/hablas-aranes\",\"name\":\"\u00bfHablas aran\u00e9s? - Trusted Translations\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/hablas-aranes#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/hablas-aranes#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Aranese-scaled.jpeg\",\"description\":\"Es poco probable que hables aran\u00e9s. Lee m\u00e1s para aprender sobre esta extra\u00f1a pero perseverante lengua de los Pirineos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/hablas-aranes#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/hablas-aranes\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/hablas-aranes#primaryimage\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Aranese-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Aranese-scaled.jpeg\",\"width\":2560,\"height\":679,\"caption\":\"Aranese scaled\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/hablas-aranes#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lenguaje\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/blog\\\/categorias\\\/lenguaje\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u00bfHablas aran\u00e9s?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"name\":\"Trusted Translations, Inc.\",\"description\":\"Leader in translation and interpretation services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\"},\"alternateName\":\"Trusted Translations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#organization\",\"name\":\"Trusted Translations\",\"alternateName\":\"Trusted Translations, Inc.\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"contentUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"width\":500,\"height\":196,\"caption\":\"Trusted Translations\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Trusted.Translations\",\"https:\\\/\\\/x.com\\\/TrustedT9ns\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/trusted-translations\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/#\\\/schema\\\/person\\\/75fa06fac744ed0db519464a2e6ad900\",\"name\":\"Trusted Translations\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/649eacd4657d3ef892bf6261b5f3934db54de3fc5187d999da33fd58697046f8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/649eacd4657d3ef892bf6261b5f3934db54de3fc5187d999da33fd58697046f8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/649eacd4657d3ef892bf6261b5f3934db54de3fc5187d999da33fd58697046f8?s=96&d=mm&r=g\",\"caption\":\"Trusted Translations\"},\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/es\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfHablas aran\u00e9s? - Trusted Translations","description":"Es poco probable que hables aran\u00e9s. Lee m\u00e1s para aprender sobre esta extra\u00f1a pero perseverante lengua de los Pirineos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes","og_locale":"es_ES","og_type":"article","og_title":"\u00bfHablas aran\u00e9s? - Trusted Translations","og_description":"Es poco probable que hables aran\u00e9s. Lee m\u00e1s para aprender sobre esta extra\u00f1a pero perseverante lengua de los Pirineos.","og_url":"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes","og_site_name":"Trusted Translations","article_publisher":"https:\/\/www.facebook.com\/Trusted.Translations","article_modified_time":"2023-01-26T15:37:36+00:00","og_image":[{"width":2560,"height":679,"url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/08\/Aranese-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TrustedT9ns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes#article","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes"},"author":{"name":"Trusted Translations","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/75fa06fac744ed0db519464a2e6ad900"},"headline":"\u00bfHablas aran\u00e9s?","datePublished":"2022-08-24T15:55:16+00:00","dateModified":"2023-01-26T15:37:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes"},"wordCount":839,"publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes#primaryimage"},"thumbnailUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/08\/Aranese-scaled.jpeg","keywords":["idioma oficial","lenguas en peligro de extinci\u00f3n","lenguas romance","official language"],"articleSection":["Lenguaje"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes","url":"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes","name":"\u00bfHablas aran\u00e9s? - Trusted Translations","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes#primaryimage"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes#primaryimage"},"thumbnailUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/08\/Aranese-scaled.jpeg","description":"Es poco probable que hables aran\u00e9s. Lee m\u00e1s para aprender sobre esta extra\u00f1a pero perseverante lengua de los Pirineos.","breadcrumb":{"@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes#primaryimage","url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/08\/Aranese-scaled.jpeg","contentUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/08\/Aranese-scaled.jpeg","width":2560,"height":679,"caption":"Aranese scaled"},{"@type":"BreadcrumbList","@id":"https:\/\/www.trustedtranslations.com\/es\/blog\/hablas-aranes#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trustedtranslations.com\/es"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.trustedtranslations.com\/es\/blog"},{"@type":"ListItem","position":3,"name":"Lenguaje","item":"https:\/\/www.trustedtranslations.com\/es\/blog\/categorias\/lenguaje"},{"@type":"ListItem","position":4,"name":"\u00bfHablas aran\u00e9s?"}]},{"@type":"WebSite","@id":"https:\/\/www.trustedtranslations.com\/es\/#website","url":"https:\/\/www.trustedtranslations.com\/es\/","name":"Trusted Translations, Inc.","description":"Leader in translation and interpretation services.","publisher":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#organization"},"alternateName":"Trusted Translations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trustedtranslations.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.trustedtranslations.com\/es\/#organization","name":"Trusted Translations","alternateName":"Trusted Translations, Inc.","url":"https:\/\/www.trustedtranslations.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","contentUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","width":500,"height":196,"caption":"Trusted Translations"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Trusted.Translations","https:\/\/x.com\/TrustedT9ns","https:\/\/www.linkedin.com\/company\/trusted-translations"]},{"@type":"Person","@id":"https:\/\/www.trustedtranslations.com\/es\/#\/schema\/person\/75fa06fac744ed0db519464a2e6ad900","name":"Trusted Translations","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/649eacd4657d3ef892bf6261b5f3934db54de3fc5187d999da33fd58697046f8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/649eacd4657d3ef892bf6261b5f3934db54de3fc5187d999da33fd58697046f8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/649eacd4657d3ef892bf6261b5f3934db54de3fc5187d999da33fd58697046f8?s=96&d=mm&r=g","caption":"Trusted Translations"},"url":"https:\/\/www.trustedtranslations.com\/es\/author\/admin"}]}},"toolset-meta":{"cpt-for-blogs":{"revisor":{"type":"textfield","raw":""},"revisor-image":{"type":"image","raw":"","attachment_id":null},"revisor-description":{"type":"textfield","raw":""},"revisor-link":{"type":"url","raw":""}}},"_links":{"self":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/157069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/comments?post=157069"}],"version-history":[{"count":0,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/blog\/157069\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/media\/156520"}],"wp:attachment":[{"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/media?parent=157069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/categories?post=157069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/es\/wp-json\/wp\/v2\/tags?post=157069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}