{"id":163781,"date":"2022-11-03T18:48:11","date_gmt":"2022-11-03T18:48:11","guid":{"rendered":"https:\/\/www.trustedtranslations.com\/?post_type=blog&#038;p=163781"},"modified":"2022-11-03T18:48:11","modified_gmt":"2022-11-03T18:48:11","slug":"la-premiere-folie-des-internautes-algospeak","status":"publish","type":"blog","link":"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak","title":{"rendered":"La premi\u00e8re folie des internautes\u00a0: l\u2019av\u00e8nement de l\u2019<i>algospeak<\/i>"},"content":{"rendered":"<p>Les langues sont des ph\u00e9nom\u00e8nes vivants. Bien que nous n\u2019y pensions pas beaucoup dans notre vie quotidienne, les langues que nous parlons changent constamment. Les langues sont essentiellement des outils qui servent \u00e0 faciliter la communication entre personnes et sont <a href=\"https:\/\/www.trustedtranslations.com\/fr\/blog\/evolution-linguistique-interstellaire\" target=\"_blank\" rel=\"noopener\">susceptibles de changer en fonction de l\u2019\u00e9volution de la soci\u00e9t\u00e9<\/a>, par exemple, lors de la transition urbaine ou lors de la transformation num\u00e9rique.<\/p>\n<p>Tu peux le v\u00e9rifier en lisant un texte en ancien anglais. Nous continuons \u00e0 l\u2019appeler <i>anglais<\/i>, mais il a tellement chang\u00e9 au cours de ces si\u00e8cles qu\u2019il nous est impossible de le comprendre sans l\u2019\u00e9tudier ou sans le traduire en anglais contemporain.<\/p>\n<p>M\u00eame \u00e0 plus petite \u00e9chelle, cependant, les langues continuent d\u2019\u00e9voluer et de changer pour r\u00e9pondre \u00e0 nos besoins et pour nous aider \u00e0 communiquer plus efficacement les uns avec les autres. De nouveaux mots sont constamment invent\u00e9s ou r\u00e9utilis\u00e9s pour mieux servir notre soci\u00e9t\u00e9 de plus en plus technologique. Si tu as \u00e9t\u00e9 sur les r\u00e9seaux sociaux, tu es s\u00fbrement tomb\u00e9 sur un <a href=\"https:\/\/www.washingtonpost.com\/technology\/2022\/04\/08\/algospeak-tiktok-le-dollar-bean\/\" target=\"_blank\" rel=\"noopener\">bel exemple des mutations linguistiques actuelles<\/a>, sans m\u00eame t\u2019en rendre compte\u00a0: il s\u2019agit de l\u2019<i>algospeak<\/i>.<\/p>\n<h2><strong>Qu\u2019est-ce que l\u2019<i>algospeak<\/i>\u00a0?<\/strong><\/h2>\n<p><i>Algospeak <\/i>est un mot tellement nouveau que le correcteur orthographique de Word ne le reconna\u00eet pas encore et le souligne en rouge sur mon \u00e9cran, comme s\u2019il s\u2019agissait d\u2019une faute d\u2019orthographe. Cette expression d\u00e9rive du mot <i>algorithme<\/i>, ce programme auquel tous les cr\u00e9ateurs de contenu sur les r\u00e9seaux sociaux doivent s\u2019adapter. L\u2019algorithme d\u00e9cide quelles publications seront promues et pr\u00e9sent\u00e9es aux utilisateurs et quelles seront cach\u00e9es en fonction d\u2019un ensemble complexe de r\u00e8gles et de crit\u00e8res. Une partie de ces crit\u00e8res consiste \u00e0 supprimer du langage (et puis du contenu) consid\u00e9r\u00e9 inappropri\u00e9 pour une certaine partie du public. Pour y parvenir, les r\u00e9seaux sociaux utilisent l\u2019intelligence artificielle, pour censurer des mots qui signalent un contenu inad\u00e9quat.<\/p>\n<p>L\u2019<i>algospeak<\/i> fait r\u00e9f\u00e9rence aux changements de langage utilis\u00e9s par les cr\u00e9ateurs de contenu pour contourner la censure. Par exemple, des mots comme <i>mort<\/i> ou <i>assassin\u00e9<\/i> sont \u00e9tiquet\u00e9s par l\u2019intelligence artificielle \u00e0 cause de son association au champ lexical de la violence. Pour contourner \u00e7a, les cr\u00e9ateurs de contenus ont commenc\u00e9 \u00e0 utiliser des syntagmes tels que <i>unalive<\/i> (sansvie) ou <i>unalived<\/i> (sansvi\u00e9) pour transmettre le m\u00eame signifi\u00e9, sans \u00eatre censur\u00e9s. Les internautes doivent recourir \u00e0 ces strat\u00e9gies pour parler de sujets controvers\u00e9s, comme l\u2019annulation de l\u2019arr\u00eat <i>Roe v. Wade<\/i> aux \u00c9tats-Unis ou la r\u00e9cente crise sanitaire.<\/p>\n<p>En fait, la pand\u00e9mie a \u00e9galement apport\u00e9 avec elle de nouveaux termes associ\u00e9s \u00e0 l\u2019<i>algospeak<\/i>. Plusieurs cr\u00e9ateurs de contenu sur TikTok et d\u2019autres plateformes utilisaient les termes \u00ab\u00a0panini\u00a0\u00bb ou \u00ab\u00a0Panda Express\u00a0\u00bb au lieu de \u2018pand\u00e9mie\u2019 pour \u00e9chapper \u00e0 l\u2019intelligence artificielle qui restreignait les vid\u00e9os \u00e9voquant cette situation, craignant la propagation de fausses informations.<\/p>\n<p>Il n\u2019y a pas de r\u00e8gles strictes pour l\u2019<i>algospeak<\/i>. Parfois, il s\u2019agit de faire des rimes ou d\u2019utiliser des mots similaires, tels que \u201cpanini\u201d au lieu de \u2018pand\u00e9mie\u2019, mais il existe \u00e9galement des termes absurdes. Par exemple, il y a des travailleurs du sexe qui se font appeler <i>comptables<\/i> pour cacher leur v\u00e9ritable profession. D\u2019une certaine mani\u00e8re, ce jargon peut nous rappeler l\u2019argot des criminels ou des banlieues des grandes villes. Bien qu\u2019il s\u2019agisse de la m\u00eame langue, les mots sont d\u00e9form\u00e9s pour tromper les auditeurs non-initi\u00e9s ou hostiles.<\/p>\n<h2><strong>Qu\u2019est-ce qui ne va pas alors\u00a0?<\/strong><\/h2>\n<p>En plus d\u2019\u00eatre un ph\u00e9nom\u00e8ne fascinant pour les passionn\u00e9s des langues, l\u2019existence de l\u2019<i>algospeak <\/i>met en \u00e9vidence les probl\u00e8mes caus\u00e9s par la censure et d\u00e9montre \u00e0 quel point il est difficile de <a href=\"https:\/\/www.forbes.com\/sites\/alexandralevine\/2022\/09\/16\/algospeak-social-media-survey\/?sh=1e36ef8555e1\" target=\"_blank\" rel=\"noopener\">concilier libert\u00e9 et s\u00e9curit\u00e9 sur Internet<\/a>, alors que cette derni\u00e8re fait de plus en plus partie int\u00e9grante de la vie quotidienne.<\/p>\n<p>D\u2019une part, une certaine censure algorithmique men\u00e9e par l\u2019intelligence artificielle dans les r\u00e9seaux sociaux peut emp\u00eacher les utilisateurs vuln\u00e9rables ou impressionnables, tels que les enfants, d\u2019\u00eatre inutilement expos\u00e9s \u00e0 des contenus potentiellement d\u00e9rangeants. En revanche, une telle censure peut rendre plus difficile la tenue d\u2019importants d\u00e9bats publics sur certains sujets sensibles, en raison d\u2019interdictions pures et simples de certains mots.<\/p>\n<p>Le fait qu\u2019il existe d\u00e9j\u00e0 des articles sur l\u2019<i>algospeak<\/i> sugg\u00e8re que les r\u00e9seaux sociaux pourraient \u00e9galement s\u2019apercevoir de son utilisation et commencer \u00e0 le combattre, censurant tout n\u00e9ologisme \u00e9vasif qui d\u00e9coule du contournement de la censure. Une chose est claire\u00a0: il n\u2019y aura pas de solution facile \u00e0 un probl\u00e8me aussi nuanc\u00e9.<\/p>\n<p>Et bien qu\u2019il s\u2019agisse d\u2019une question complexe, il est int\u00e9ressant de voir comment nous, en tant que soci\u00e9t\u00e9, g\u00e9rons les progr\u00e8s des technologies num\u00e9riques et quelles limites devraient \u00eatre plac\u00e9es pour pr\u00e9venir les abus. Le temps r\u00e9v\u00e9lera les changements que cela provoquera dans les diff\u00e9rentes langues. Personne ne le sait encore. Mais peut-\u00eatre qu\u2019un jour <em><em>Trusted Translations<\/em><\/em> devra ajouter l\u2019<i>algospeak <\/i>\u00e0 ses services de traduction.<\/p>\n<p>Photo de \u0414\u043c\u0438\u0442\u0440\u0438\u0439 \u0425\u0440\u0443\u0441\u0442\u0430\u043b\u0435\u0432-\u0413\u0440\u0438\u0433\u043e\u0440\u044c\u0435\u0432 sur Unsplash<\/p>\n","protected":false},"excerpt":{"rendered":"Les langues sont des ph\u00e9nom\u00e8nes vivants. Bien que nous n\u2019y pensions pas beaucoup dans notre vie quotidienne, les langues que nous parlons changent constamment. Les langues sont essentiellement des outils\u2026\n","protected":false},"author":113,"featured_media":163290,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[17432],"tags":[17903,17904,17854,8873],"class_list":["post-163781","blog","type-blog","status-publish","format-standard","has-post-thumbnail","hentry","category-langues-fr","tag-langues-inventees-fr","tag-langues-secretes","tag-secret-language","tag-social-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La premi\u00e8re folie des internautes\u00a0: l\u2019av\u00e8nement de l\u2019algospeak - Trusted Translations, Inc.<\/title>\n<meta name=\"description\" content=\"La censure dans les r\u00e9seaux sociaux d\u00e9rive dans l\u2019apparition d\u2019un nouvel argot. D\u00e9couvre l\u2019algospeak et ce que cela signifie pour la communication.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La premi\u00e8re folie des internautes\u00a0: l\u2019av\u00e8nement de l\u2019algospeak - Trusted Translations, Inc.\" \/>\n<meta property=\"og:description\" content=\"La censure dans les r\u00e9seaux sociaux d\u00e9rive dans l\u2019apparition d\u2019un nouvel argot. D\u00e9couvre l\u2019algospeak et ce que cela signifie pour la communication.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak\" \/>\n<meta property=\"og:site_name\" content=\"Trusted Translations, Inc.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Trusted.Translations\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/10\/masks-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TrustedT9ns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/la-premiere-folie-des-internautes-algospeak#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/la-premiere-folie-des-internautes-algospeak\"},\"author\":{\"name\":\"Alex Hubbard\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#\\\/schema\\\/person\\\/bdcbb227c3e573e9edf0f145348fc066\"},\"headline\":\"La premi\u00e8re folie des internautes\u00a0: l\u2019av\u00e8nement de l\u2019algospeak\",\"datePublished\":\"2022-11-03T18:48:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/la-premiere-folie-des-internautes-algospeak\"},\"wordCount\":915,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/la-premiere-folie-des-internautes-algospeak#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/masks-scaled.jpg\",\"keywords\":[\"langues invent\u00e9es\",\"langues secr\u00e8tes\",\"secret language\",\"Social Media\"],\"articleSection\":[\"Langues\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/la-premiere-folie-des-internautes-algospeak\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/la-premiere-folie-des-internautes-algospeak\",\"name\":\"La premi\u00e8re folie des internautes\u00a0: l\u2019av\u00e8nement de l\u2019algospeak - Trusted Translations, Inc.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/la-premiere-folie-des-internautes-algospeak#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/la-premiere-folie-des-internautes-algospeak#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/masks-scaled.jpg\",\"description\":\"La censure dans les r\u00e9seaux sociaux d\u00e9rive dans l\u2019apparition d\u2019un nouvel argot. D\u00e9couvre l\u2019algospeak et ce que cela signifie pour la communication.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/la-premiere-folie-des-internautes-algospeak#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/la-premiere-folie-des-internautes-algospeak\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/la-premiere-folie-des-internautes-algospeak#primaryimage\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/masks-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/masks-scaled.jpg\",\"width\":1707,\"height\":2560,\"caption\":\"masks scaled\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/la-premiere-folie-des-internautes-algospeak#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Langues\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/category\\\/langues-fr\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"La premi\u00e8re folie des internautes\u00a0: l\u2019av\u00e8nement de l\u2019algospeak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/\",\"name\":\"Trusted Translations, Inc.\",\"description\":\"Leader in translation and interpretation services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#organization\"},\"alternateName\":\"Trusted Translations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#organization\",\"name\":\"Trusted Translations\",\"alternateName\":\"Trusted Translations, Inc.\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"contentUrl\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"width\":500,\"height\":196,\"caption\":\"Trusted Translations\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Trusted.Translations\",\"https:\\\/\\\/x.com\\\/TrustedT9ns\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/trusted-translations\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#\\\/schema\\\/person\\\/bdcbb227c3e573e9edf0f145348fc066\",\"name\":\"Alex Hubbard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/daa5c4ea09ec859f27375bc23b133648ed152e67f9b391add4ebbb705279f7ff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/daa5c4ea09ec859f27375bc23b133648ed152e67f9b391add4ebbb705279f7ff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/daa5c4ea09ec859f27375bc23b133648ed152e67f9b391add4ebbb705279f7ff?s=96&d=mm&r=g\",\"caption\":\"Alex Hubbard\"},\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/author\\\/alexh\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La premi\u00e8re folie des internautes\u00a0: l\u2019av\u00e8nement de l\u2019algospeak - Trusted Translations, Inc.","description":"La censure dans les r\u00e9seaux sociaux d\u00e9rive dans l\u2019apparition d\u2019un nouvel argot. D\u00e9couvre l\u2019algospeak et ce que cela signifie pour la communication.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak","og_locale":"fr_FR","og_type":"article","og_title":"La premi\u00e8re folie des internautes\u00a0: l\u2019av\u00e8nement de l\u2019algospeak - Trusted Translations, Inc.","og_description":"La censure dans les r\u00e9seaux sociaux d\u00e9rive dans l\u2019apparition d\u2019un nouvel argot. D\u00e9couvre l\u2019algospeak et ce que cela signifie pour la communication.","og_url":"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak","og_site_name":"Trusted Translations, Inc.","article_publisher":"https:\/\/www.facebook.com\/Trusted.Translations","og_image":[{"width":1707,"height":2560,"url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/10\/masks-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TrustedT9ns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak#article","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak"},"author":{"name":"Alex Hubbard","@id":"https:\/\/www.trustedtranslations.com\/fr\/#\/schema\/person\/bdcbb227c3e573e9edf0f145348fc066"},"headline":"La premi\u00e8re folie des internautes\u00a0: l\u2019av\u00e8nement de l\u2019algospeak","datePublished":"2022-11-03T18:48:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak"},"wordCount":915,"publisher":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak#primaryimage"},"thumbnailUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/10\/masks-scaled.jpg","keywords":["langues invent\u00e9es","langues secr\u00e8tes","secret language","Social Media"],"articleSection":["Langues"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak","url":"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak","name":"La premi\u00e8re folie des internautes\u00a0: l\u2019av\u00e8nement de l\u2019algospeak - Trusted Translations, Inc.","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak#primaryimage"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak#primaryimage"},"thumbnailUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/10\/masks-scaled.jpg","description":"La censure dans les r\u00e9seaux sociaux d\u00e9rive dans l\u2019apparition d\u2019un nouvel argot. D\u00e9couvre l\u2019algospeak et ce que cela signifie pour la communication.","breadcrumb":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak#primaryimage","url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/10\/masks-scaled.jpg","contentUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/10\/masks-scaled.jpg","width":1707,"height":2560,"caption":"masks scaled"},{"@type":"BreadcrumbList","@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/la-premiere-folie-des-internautes-algospeak#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.trustedtranslations.com\/fr"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.trustedtranslations.com\/fr\/blog"},{"@type":"ListItem","position":3,"name":"Langues","item":"https:\/\/www.trustedtranslations.com\/fr\/blog\/category\/langues-fr"},{"@type":"ListItem","position":4,"name":"La premi\u00e8re folie des internautes\u00a0: l\u2019av\u00e8nement de l\u2019algospeak"}]},{"@type":"WebSite","@id":"https:\/\/www.trustedtranslations.com\/fr\/#website","url":"https:\/\/www.trustedtranslations.com\/fr\/","name":"Trusted Translations, Inc.","description":"Leader in translation and interpretation services.","publisher":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/#organization"},"alternateName":"Trusted Translations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trustedtranslations.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.trustedtranslations.com\/fr\/#organization","name":"Trusted Translations","alternateName":"Trusted Translations, Inc.","url":"https:\/\/www.trustedtranslations.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.trustedtranslations.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","contentUrl":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","width":500,"height":196,"caption":"Trusted Translations"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Trusted.Translations","https:\/\/x.com\/TrustedT9ns","https:\/\/www.linkedin.com\/company\/trusted-translations"]},{"@type":"Person","@id":"https:\/\/www.trustedtranslations.com\/fr\/#\/schema\/person\/bdcbb227c3e573e9edf0f145348fc066","name":"Alex Hubbard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/daa5c4ea09ec859f27375bc23b133648ed152e67f9b391add4ebbb705279f7ff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/daa5c4ea09ec859f27375bc23b133648ed152e67f9b391add4ebbb705279f7ff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/daa5c4ea09ec859f27375bc23b133648ed152e67f9b391add4ebbb705279f7ff?s=96&d=mm&r=g","caption":"Alex Hubbard"},"url":"https:\/\/www.trustedtranslations.com\/fr\/author\/alexh"}]}},"toolset-meta":{"cpt-for-blogs":{"revisor":{"type":"textfield","raw":""},"revisor-image":{"type":"image","raw":"","attachment_id":null},"revisor-description":{"type":"textfield","raw":""},"revisor-link":{"type":"url","raw":""}}},"_links":{"self":[{"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/blog\/163781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/comments?post=163781"}],"version-history":[{"count":0,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/blog\/163781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/media\/163290"}],"wp:attachment":[{"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/media?parent=163781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/categories?post=163781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/tags?post=163781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}