{"id":192799,"date":"2023-03-09T11:00:01","date_gmt":"2023-03-09T14:00:01","guid":{"rendered":"https:\/\/www.trustedtranslations.com\/?post_type=blog&#038;p=192799"},"modified":"2023-03-08T23:23:08","modified_gmt":"2023-03-09T02:23:08","slug":"traductions-superstitieuses","status":"publish","type":"blog","link":"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses","title":{"rendered":"Traductions superstitieuses"},"content":{"rendered":"<p>Alors que la langue refl\u00e8te certainement l&rsquo;\u00e2me d&rsquo;un peuple, les superstitions repr\u00e9sentent souvent son histoire et sa culture.<\/p>\n<p>Voici donc un aper\u00e7u de certaines fa\u00e7ons dont les anciennes croyances influencent encore la vie des gens.<\/p>\n<p>Entrelac\u00e9es avec les cultures et histoires des peuples, les superstitions relient le monde contemporain \u00e0 l\u2019Antiquit\u00e9. On croit g\u00e9n\u00e9ralement que le r\u00e9cit de la C\u00e8ne est la raison pour laquelle treize est associ\u00e9 \u00e0 la malchance. Et plus de 2\u00a0000 ans plus tard, les ma\u00eetresses de maison veillent \u00e0 \u00e9viter que les convives se r\u00e9unissent au nombre de treize \u00e0 table.<\/p>\n<p>Mais dans une tournure \u00e9trange du destin, treize est un chiffre porte-bonheur en Italie et en France, o\u00f9 le <em>vendredi 13<\/em> (ou bien <em><i>venerd\u00ec 13<\/i><\/em>) est consid\u00e9r\u00e9 comme un jour propice. C&rsquo;est aussi un num\u00e9ro fr\u00e9quent pour parier sur les matchs de football.<\/p>\n<p>En revanche, le vendredi 17 en Italie est consid\u00e9r\u00e9 comme malchanceux, car le chiffre romain XVII est associ\u00e9 \u00e0 la mort. Le XVII est une anagramme de <em><i>vixi<\/i><\/em>, qui signifie \u00ab <em>j\u2019ai v\u00e9cu<\/em> \u00bb et sugg\u00e8re que l\u2019on ne vit plus. Et cela est de mauvais augure pour n\u2019importe quel jour de la semaine !<\/p>\n<h2><strong>Le plus ancien symbole de bonne chance\u00a0? <\/strong><\/h2>\n<p>Les tr\u00e8fles \u00e0 quatre feuilles pourraient \u00eatre le plus ancien des symboles de bonne chance, remontant directement au jardin d&rsquo;Eden. La l\u00e9gende raconte qu\u2019Eve, apr\u00e8s avoir \u00e9t\u00e9 chass\u00e9e du paradis, aurait emport\u00e9 en souvenir un tr\u00e8fle \u00e0 quatre feuilles dont les descendants conservent quelque chose de la beaut\u00e9 du jardin d\u2019Eden.<\/p>\n<p>Les Celtes croyaient que ces tr\u00e8fles avec une feuille additionnelle poss\u00e9daient des pouvoirs magiques de protection contre le mal. Peut-\u00eatre le r\u00e9sultat d\u2019un syncr\u00e9tisme entre les symboles celtes et la foi chr\u00e9tienne, on croit saint Patrice utilisait le tr\u00e8fle pour expliquer la Trinit\u00e9 : les feuilles repr\u00e9sentaient le P\u00e8re, le Fils et l\u2019Esprit Saint. Et plus avant, le tr\u00e8fle \u00e0 quatre feuilles en est venu \u00e0 repr\u00e9senter la foi, l&rsquo;espoir, l&rsquo;amour et la bonne fortune\u00a0\u2014\u00a0on peut dire que c\u2019est un m\u00e9lange des deux traditions.<\/p>\n<h2><strong>Si les regards pouvaient tuer<\/strong><\/h2>\n<p>La mal\u00e9diction du mauvais \u0153il existe depuis le temps des \u00e9tablissements sum\u00e9riens au bord de l\u2019Euphrate il y a 5\u00a0000 ans. On leur attribue l&rsquo;invention des amulettes contre le mauvais \u0153il : les cercles blancs \u00e0 centre bleu que l\u2019on trouve souvent dans les souks et dans les \u00e9tals de march\u00e9 tout autour de la M\u00e9diterran\u00e9e.<\/p>\n<p>En Turquie, on prot\u00e8ge les nouveau-n\u00e9s en frottant ces amulettes sur leurs v\u00eatements et sur leurs berceaux. Aussi connus sous le nom d\u2019\u0153il d&rsquo;Allah, ces yeux bleus prot\u00e8gent de nombreuses maisons musulmanes. Lorsque l&rsquo;un de ces yeux est bris\u00e9 on dit qu\u2019il a absorb\u00e9 une mal\u00e9diction et doit \u00eatre remplac\u00e9 imm\u00e9diatement pour assurer une protection continue.<\/p>\n<h2><strong>Doigts crois\u00e9s<\/strong><\/h2>\n<p>Une fa\u00e7on plus moderne de repousser le mauvais \u0153il consiste \u00e0 croiser les deux premiers doigts pour faire une croix. Cela vient du sud de l&rsquo;Italie, o\u00f9 l&rsquo;on croyait qu&rsquo;un <em><i>ietattore<\/i><\/em> (du latin <em><i>iactare<\/i><\/em>, qui signifie \u00ab\u00a0jeter\u00a0\u00bb) pouvait ruiner la vie d&rsquo;une victime simplement en lui jetant le <em><i>malocchio<\/i><\/em> (\u00ab\u00a0mauvais \u0153il\u00a0\u00bb).<\/p>\n<p>M\u00eame le pape Pie IX (1792-1878) fut accus\u00e9 d&rsquo;\u00eatre un <em><i>ietattore<\/i><\/em>, prouvant que personne n\u2019est exempt de cette calomnie superstitieuse, pas m\u00eame le chef de l&rsquo;\u00c9glise. On dit que lorsque les fid\u00e8les agenouillaient devant <em>Pio Nono<\/em> pour recevoir des b\u00e9n\u00e9dictions, beaucoup faisaient le geste de la figue pour se prot\u00e9ger du mauvais \u0153il.<\/p>\n<h2><strong>Toucher ou frapper du bois<\/strong><\/h2>\n<p>Enracin\u00e9e dans le paganisme, cette ancienne superstition refl\u00e8te la croyance selon laquelle les arbres, en particulier les ch\u00eanes et les saules, sont des demeures sacr\u00e9es pour les esprits. Apr\u00e8s avoir laiss\u00e9 \u00e9chapper une l\u00e9g\u00e8re vantardise, certaines personnes crient \u00ab\u00a0<em><em>Touchons du bois<\/em><\/em>\u00a0!\u00a0\u00bb, pour apaiser les esprits qui cherchent \u00e0 punir <em>l&rsquo;arrogance<\/em>.<\/p>\n<p>Sans surprise, de nombreuses autres plantes sont cens\u00e9es porter chance ou prot\u00e9ger contre le malheur.<\/p>\n<ul>\n<li>Dans une grande partie de l&rsquo;Am\u00e9rique latine, manger <em>douze raisins<\/em> \u00e0 minuit le 31 d\u00e9cembre, un raisin pour chaque coup de cloche, assure une nouvelle ann\u00e9e prosp\u00e8re.<\/li>\n<li>Les lentilles, g\u00e9n\u00e9ralement accompagn\u00e9es de saucisses, sont un incontournable des festivit\u00e9s du Nouvel An en Italie, o\u00f9 elles symbolisent la prosp\u00e9rit\u00e9.<\/li>\n<li>Les brindilles de <em><em>rue<\/em><\/em> sont souvent cach\u00e9s derri\u00e8re les oreilles ou suspendus au-dessus des portes et des berceaux. Cette herbe est cens\u00e9e \u00e9loigner les mauvais esprits.<\/li>\n<\/ul>\n<h2><strong>Avez-vous du feu, s\u2019il vous pla\u00eet\u00a0?<\/strong><\/h2>\n<p>\u00c0 l&rsquo;\u00e9poque o\u00f9 fumer favorisait la fraternit\u00e9, allumer trois cigarettes avec la m\u00eame allumette \u00e9tait tabou dans une grande partie de l&rsquo;Europe occidentale au XXe si\u00e8cle.<\/p>\n<p>Ce mythe a peut-\u00eatre fleuri dans les tranch\u00e9es de la Premi\u00e8re Guerre mondiale : le premier fumeur attire l&rsquo;attention du tireur\u00a0; le deuxi\u00e8me lui laisse le temps de viser ; et le troisi\u00e8me est finalement abattu.<\/p>\n<h2><strong>Tromper le destin pour la bonne fortune<\/strong><\/h2>\n<p>Une fa\u00e7on linguistiquement intrigante de souhaiter bonne chance \u00e0 quelqu&rsquo;un (en particulier aux acteurs) consiste \u00e0 les maudire, en esp\u00e9rant que les dieux jaloux n\u00e9gligeront leur bonne fortune. Les Anglais souhaitent souvent aux acteurs une jambe cass\u00e9e : <em>\u00ab\u00a0Break a leg!\u00a0\u00bb. <\/em><\/p>\n<p>L&rsquo;italien a sa propre version de ce souhait n\u00e9gatif d&rsquo;un r\u00e9sultat positif\u00a0: <em>\u00ab\u00a0In bocca al lupo!\u00a0\u00bb. <\/em>Mais inciter quelqu&rsquo;un \u00e0 <em>se jeter dans la gueule du loup<\/em> est en r\u00e9alit\u00e9 destin\u00e9 \u00e0 parer au malheur.<\/p>\n<p><strong>Conclusion<\/strong>\u00a0: les superstitions sont communes \u00e0 toutes les croyances et \u00e0 tous les pays. Mais il faut un expert, comme les linguistes de <a href=\"https:\/\/www.trustedtranslations.com\/fr\/services\"><em><em>Trusted Translations<\/em><\/em><\/a>, pour s&rsquo;assurer que ces croyances sont correctement transmises de mani\u00e8re culturellement acceptable.<\/p>\n<p>Photo de Meruyert Gonullu sur pexels<\/p>\n","protected":false},"excerpt":{"rendered":"Alors que la langue refl\u00e8te certainement l\u2019\u00e2me d\u2019un peuple, les superstitions repr\u00e9sentent souvent son histoire et sa culture. Voici donc un aper\u00e7u de certaines fa\u00e7ons dont les anciennes croyances influencent\u2026\n","protected":false},"author":115,"featured_media":188073,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8232],"tags":[18567,18569,18568],"class_list":["post-192799","blog","type-blog","status-publish","format-standard","has-post-thumbnail","hentry","category-culture-2","tag-croyances","tag-langage-superstitieux","tag-superstitions-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Traductions superstitieuses - Trusted Translations, Inc.<\/title>\n<meta name=\"description\" content=\"Pour quoi la superstition est-elle si r\u00e9pandue parmi les diff\u00e9rentes cultures\u00a0? Et comment s\u2019exprime-t-elle dans diverses langues\u00a0? Comment les superstitions se traduisent-elles d&#039;une culture \u00e0 l&#039;autre ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traductions superstitieuses - Trusted Translations, Inc.\" \/>\n<meta property=\"og:description\" content=\"Pour quoi la superstition est-elle si r\u00e9pandue parmi les diff\u00e9rentes cultures\u00a0? Et comment s\u2019exprime-t-elle dans diverses langues\u00a0? Comment les superstitions se traduisent-elles d&#039;une culture \u00e0 l&#039;autre ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses\" \/>\n<meta property=\"og:site_name\" content=\"Trusted Translations, Inc.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Trusted.Translations\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2023\/02\/superstition-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TrustedT9ns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/traductions-superstitieuses#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/traductions-superstitieuses\"},\"author\":{\"name\":\"Rafael Dos Santos\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#\\\/schema\\\/person\\\/dd8c03f4a3b77ace16658b5e0bf11828\"},\"headline\":\"Traductions superstitieuses\",\"datePublished\":\"2023-03-09T14:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/traductions-superstitieuses\"},\"wordCount\":995,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/traductions-superstitieuses#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/superstition-scaled.jpg\",\"keywords\":[\"croyances\",\"langage superstitieux\",\"superstitions\"],\"articleSection\":[\"Culture\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/traductions-superstitieuses\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/traductions-superstitieuses\",\"name\":\"Traductions superstitieuses - Trusted Translations, Inc.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/traductions-superstitieuses#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/traductions-superstitieuses#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/superstition-scaled.jpg\",\"description\":\"Pour quoi la superstition est-elle si r\u00e9pandue parmi les diff\u00e9rentes cultures\u00a0? Et comment s\u2019exprime-t-elle dans diverses langues\u00a0? Comment les superstitions se traduisent-elles d'une culture \u00e0 l'autre ?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/traductions-superstitieuses#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/traductions-superstitieuses\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/traductions-superstitieuses#primaryimage\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/superstition-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/superstition-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"superstition scaled\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/traductions-superstitieuses#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Culture\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/category\\\/culture-fr\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Traductions superstitieuses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/\",\"name\":\"Trusted Translations, Inc.\",\"description\":\"Leader in translation and interpretation services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#organization\"},\"alternateName\":\"Trusted Translations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#organization\",\"name\":\"Trusted Translations\",\"alternateName\":\"Trusted Translations, Inc.\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"contentUrl\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"width\":500,\"height\":196,\"caption\":\"Trusted Translations\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Trusted.Translations\",\"https:\\\/\\\/x.com\\\/TrustedT9ns\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/trusted-translations\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#\\\/schema\\\/person\\\/dd8c03f4a3b77ace16658b5e0bf11828\",\"name\":\"Rafael Dos Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/26331e7a694d2e04a19be311cb2030dd84efd4746ad6690ce40e02b02cf8ec6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/26331e7a694d2e04a19be311cb2030dd84efd4746ad6690ce40e02b02cf8ec6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/26331e7a694d2e04a19be311cb2030dd84efd4746ad6690ce40e02b02cf8ec6b?s=96&d=mm&r=g\",\"caption\":\"Rafael Dos Santos\"},\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/author\\\/rafaelds\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Traductions superstitieuses - Trusted Translations, Inc.","description":"Pour quoi la superstition est-elle si r\u00e9pandue parmi les diff\u00e9rentes cultures\u00a0? Et comment s\u2019exprime-t-elle dans diverses langues\u00a0? Comment les superstitions se traduisent-elles d'une culture \u00e0 l'autre ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses","og_locale":"fr_FR","og_type":"article","og_title":"Traductions superstitieuses - Trusted Translations, Inc.","og_description":"Pour quoi la superstition est-elle si r\u00e9pandue parmi les diff\u00e9rentes cultures\u00a0? Et comment s\u2019exprime-t-elle dans diverses langues\u00a0? Comment les superstitions se traduisent-elles d'une culture \u00e0 l'autre ?","og_url":"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses","og_site_name":"Trusted Translations, Inc.","article_publisher":"https:\/\/www.facebook.com\/Trusted.Translations","og_image":[{"width":2560,"height":1707,"url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2023\/02\/superstition-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TrustedT9ns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses#article","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses"},"author":{"name":"Rafael Dos Santos","@id":"https:\/\/www.trustedtranslations.com\/fr\/#\/schema\/person\/dd8c03f4a3b77ace16658b5e0bf11828"},"headline":"Traductions superstitieuses","datePublished":"2023-03-09T14:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses"},"wordCount":995,"publisher":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses#primaryimage"},"thumbnailUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2023\/02\/superstition-scaled.jpg","keywords":["croyances","langage superstitieux","superstitions"],"articleSection":["Culture"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses","url":"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses","name":"Traductions superstitieuses - Trusted Translations, Inc.","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses#primaryimage"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses#primaryimage"},"thumbnailUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2023\/02\/superstition-scaled.jpg","description":"Pour quoi la superstition est-elle si r\u00e9pandue parmi les diff\u00e9rentes cultures\u00a0? Et comment s\u2019exprime-t-elle dans diverses langues\u00a0? Comment les superstitions se traduisent-elles d'une culture \u00e0 l'autre ?","breadcrumb":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses#primaryimage","url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2023\/02\/superstition-scaled.jpg","contentUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2023\/02\/superstition-scaled.jpg","width":2560,"height":1707,"caption":"superstition scaled"},{"@type":"BreadcrumbList","@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/traductions-superstitieuses#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.trustedtranslations.com\/fr"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.trustedtranslations.com\/fr\/blog"},{"@type":"ListItem","position":3,"name":"Culture","item":"https:\/\/www.trustedtranslations.com\/fr\/blog\/category\/culture-fr"},{"@type":"ListItem","position":4,"name":"Traductions superstitieuses"}]},{"@type":"WebSite","@id":"https:\/\/www.trustedtranslations.com\/fr\/#website","url":"https:\/\/www.trustedtranslations.com\/fr\/","name":"Trusted Translations, Inc.","description":"Leader in translation and interpretation services.","publisher":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/#organization"},"alternateName":"Trusted Translations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trustedtranslations.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.trustedtranslations.com\/fr\/#organization","name":"Trusted Translations","alternateName":"Trusted Translations, Inc.","url":"https:\/\/www.trustedtranslations.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.trustedtranslations.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","contentUrl":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","width":500,"height":196,"caption":"Trusted Translations"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Trusted.Translations","https:\/\/x.com\/TrustedT9ns","https:\/\/www.linkedin.com\/company\/trusted-translations"]},{"@type":"Person","@id":"https:\/\/www.trustedtranslations.com\/fr\/#\/schema\/person\/dd8c03f4a3b77ace16658b5e0bf11828","name":"Rafael Dos Santos","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/26331e7a694d2e04a19be311cb2030dd84efd4746ad6690ce40e02b02cf8ec6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/26331e7a694d2e04a19be311cb2030dd84efd4746ad6690ce40e02b02cf8ec6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/26331e7a694d2e04a19be311cb2030dd84efd4746ad6690ce40e02b02cf8ec6b?s=96&d=mm&r=g","caption":"Rafael Dos Santos"},"url":"https:\/\/www.trustedtranslations.com\/fr\/author\/rafaelds"}]}},"toolset-meta":{"cpt-for-blogs":{"revisor":{"type":"textfield","raw":""},"revisor-image":{"type":"image","raw":"","attachment_id":null},"revisor-description":{"type":"textfield","raw":""},"revisor-link":{"type":"url","raw":""}}},"_links":{"self":[{"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/blog\/192799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/users\/115"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/comments?post=192799"}],"version-history":[{"count":0,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/blog\/192799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/media\/188073"}],"wp:attachment":[{"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/media?parent=192799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/categories?post=192799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/tags?post=192799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}