{"id":218143,"date":"2023-08-10T13:10:32","date_gmt":"2023-08-10T16:10:32","guid":{"rendered":"https:\/\/www.trustedtranslations.com\/?post_type=blog&#038;p=218143"},"modified":"2023-08-10T13:10:32","modified_gmt":"2023-08-10T16:10:32","slug":"les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile","status":"publish","type":"blog","link":"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile","title":{"rendered":"Les p\u00e9rils de la traduction IA dans les contextes de demande d\u2019asile"},"content":{"rendered":"<p>Les r\u00e9fugi\u00e9s se retrouvent dans une situation singuli\u00e8rement pr\u00e9caire, frustrante, effrayante. Ils ont \u00e9t\u00e9 d\u00e9plac\u00e9s de chez eux et sont oblig\u00e9s d\u2019essayer d\u2019\u00eatre admis \u00e0 entrer dans un pays \u00e9tranger. Un pays dont la langue officielle est souvent diff\u00e9rente de la leur. C\u2019est une situation que la plupart des gens ont le privil\u00e8ge d\u2019\u00e9viter. Cet \u00e9v\u00e9nement bouleversant \u00e9chappe totalement au contr\u00f4le des r\u00e9fugi\u00e9s. Ainsi, la tendance r\u00e9cente de certaines organisations et agences gouvernementales \u00e0 refuser effectivement \u00e0 ces personnes l\u2019acc\u00e8s \u00e0 des traducteurs experts pour compl\u00e9ter des documents critiques \u2014\u00a0et \u00e0 laisser qu\u2019ils se d\u00e9brouillent avec des logiciels de traduction automatique\u00a0\u2014 est choquante.<\/p>\n<p>Bien que la traduction automatique se soit beaucoup am\u00e9lior\u00e9e au cours de la derni\u00e8re d\u00e9cennie, elle est encore insuffisante, ce qui la rend inadmissible dans les situations de vie ou de mort dans lesquelles les r\u00e9fugi\u00e9s peuvent se trouver. Les demandeurs d\u2019asile doivent remplir les formulaires requis avec des informations pr\u00e9cises. Et la pr\u00e9cision, dans ce cas, n\u00e9cessite les services de professionnels qualifi\u00e9s.<\/p>\n<h2>Traducteurs et r\u00e9fugi\u00e9s<\/h2>\n<p>Lorsqu\u2019un r\u00e9fugi\u00e9 demande l\u2019asile dans plusieurs pays, il devra probablement faire face \u00e0 ces circonstances ayant peu (ou n\u2019ayant pas) de connaissance de la langue du pays. C\u2019est normal. Apr\u00e8s tout, ce n\u2019\u00e9tait pas une excursion pr\u00e9vue. Les r\u00e9fugi\u00e9s n\u2019ont toujours pas le choix. En <a href=\"https:\/\/restofworld.org\/2023\/ai-translation-errors-afghan-refugees-asylum\/\" target=\"_blank\" rel=\"noopener\">travaillant<\/a> avec eux, les traducteurs peuvent aider ces r\u00e9fugi\u00e9s \u00e0 se frayer un chemin \u00e0 travers des syst\u00e8mes d\u2019immigration complexes, ce qui comprend l\u2019assemblage de divers formulaires d\u2019immigration tels que les demandes d\u2019asile.<\/p>\n<p>Sans cette assistance, il est difficile d\u2019imaginer comment un r\u00e9fugi\u00e9 pourrait comprendre clairement ce qui lui est demand\u00e9, et encore moins comment y r\u00e9pondre.<\/p>\n<p>Uma Mirkhail, une traductrice sp\u00e9cialis\u00e9e en crises qui travaille avec Respond Crisis Translation, a racont\u00e9 \u00e0 <em>Rest of the World<\/em> une situation o\u00f9 le manque d\u2019assistance a eu des cons\u00e9quences catastrophiques. En 2020, Mirkhail a travaill\u00e9 avec une locutrice du pachto, une r\u00e9fugi\u00e9e qui avait fui l\u2019Afghanistan vers les \u00c9tats-Unis et dont la demande d\u2019asile avait \u00e9t\u00e9 refus\u00e9e parce qu\u2019elle diff\u00e9rait de la r\u00e9ponse \u00e0 l\u2019entretien initial.<\/p>\n<p>La raison \u00e9tait simple\u00a0: un outil de traduction automatique avait remplac\u00e9 les pronoms de la premi\u00e8re personne du singulier dans la d\u00e9claration de la r\u00e9fugi\u00e9e par des pronoms de la premi\u00e8re personne du pluriel, cr\u00e9ant une divergence entre son entretien initial et ce qui \u00e9tait \u00e9crit dans sa demande d\u2019asile. Cette diff\u00e9rence \u00e9tait une cause suffisante pour le rejet.<\/p>\n<p>Comme l\u2019a d\u00e9clar\u00e9 Leila Lorenzo, directrice des politiques chez Respond Crisis Translation, dans une interview avec <em>Rest of the World<\/em>, non seulement les traducteurs perdent leur emploi avec l\u2019essor des applications et de la traduction automatique, mais en plus, des demandes d\u2019asile d\u00e9j\u00e0 pr\u00e9caires risquent d\u2019\u00eatre refus\u00e9es.<\/p>\n<p>Au Royaume-Uni, un document du minist\u00e8re de l\u2019Int\u00e9rieur (Home Office) divulgu\u00e9 par le journal <em>The Guardian<\/em> en f\u00e9vrier a r\u00e9v\u00e9l\u00e9 de nouveaux plans pour tenter d\u2019\u00e9liminer l\u2019accumulation de demandes d\u2019asile. Ces plans comprennent un questionnaire de plus de cinquante questions qui remplacerait les entretiens en personne dans le cadre du Streamlined Asylum Processing (Traitement simplifi\u00e9 de l\u2019asile). La directive officielle pour ceux qui ont des comp\u00e9tences limit\u00e9es en langue anglaise serait de demander de l\u2019aide \u00e0 leur famille ou \u00e0 leurs amis, ou d\u2019utiliser des outils de traduction en ligne.<\/p>\n<h2>Assurer un soutien ad\u00e9quat<\/h2>\n<p>Veiller \u00e0 ce que les demandeurs d\u2019asile aient une chance \u00e9quitable signifie s\u2019assurer qu\u2019ils b\u00e9n\u00e9ficient d\u2019un soutien ad\u00e9quat. Il doit y avoir une aide r\u00e9elle, comme fournir des traducteurs experts qui peuvent \u00e9viter le genre d\u2019erreurs que commettent les outils et les logiciels de traduction. Les gouvernements \u2014\u00a0ou leurs sous-traitants\u00a0\u2014 et les organisations d\u2019aide travaillant avec les demandeurs d\u2019asile ne peuvent pas continuer \u00e0 s\u2019appuyer sur une technologie inefficace si leur objectif est de donner une chance \u00e9quitable aux demandeurs d\u2019asile.<\/p>\n<p>Bien s\u00fbr, la <a href=\"https:\/\/www.trustedtranslations.com\/fr\/services\/traduction-automatique\">traduction automatique<\/a> et l\u2019IA continuent d\u2019\u00eatre des d\u00e9veloppements int\u00e9ressants, mais la traduction reste une t\u00e2che difficile. Cela va au-del\u00e0 d\u2019une simple traduction mot \u00e0 mot. Le contexte d\u2019une phrase peut influencer le sens d\u2019un seul mot de telle mani\u00e8re que la technologie ne peut pas le d\u00e9tecter, ce qui conduit \u00e0 de simples erreurs. C\u2019est comme dans le cas d\u00e9crit par Mirkhail. Un <a href=\"https:\/\/www.trustedtranslations.com\/fr\/services\/humaine\">traducteur humain<\/a> peut se frayer un chemin \u00e0 travers ces complexit\u00e9s. Et cela s\u2019ajoute aux complexit\u00e9s introduites par les m\u00e9taphores et les expressions idiomatiques qui peuvent appara\u00eetre dans la d\u00e9claration personnelle d\u2019un r\u00e9fugi\u00e9.<\/p>\n<p>Damian Harris-Hernandez, co-fondateur du <em>Refugee Translation Project<\/em>, souligne ces probl\u00e8mes, soulignant \u00e9galement qu\u2019au fond, \u00ab\u00a0l\u2019\u00e9criture de la personne n\u2019est peut-\u00eatre pas parfaite\u00a0\u00bb.<\/p>\n<p>Deux des langues les plus demand\u00e9es au <em>Refugee Translation Project<\/em> sont le dari et le pachto. Mais il n\u2019y a pas eu autant de d\u00e9veloppement dans les outils de traduction en ce qui concerne ces deux langues. La raison de cet \u00e9cart est que, d\u2019une mani\u00e8re g\u00e9n\u00e9rale, l\u2019anglais et le chinois mandarin ont une priorit\u00e9 plus \u00e9lev\u00e9e.<\/p>\n<p>L\u2019embauche de <a href=\"https:\/\/www.trustedtranslations.com\/fr\">traducteurs<\/a> vaut la peine si l\u2019on tient compte des besoins des r\u00e9fugi\u00e9s. Les traducteurs peuvent s\u2019assurer que les demandeurs d\u2019asile communiquent des informations avec pr\u00e9cision lorsqu\u2019ils remplissent des formulaires, pr\u00e9parent des documents ou font des d\u00e9clarations. <em><em>Trusted Translations<\/em><\/em> offre les services de linguistes professionnels du monde entier, travaillant dans un large \u00e9ventail de <a href=\"https:\/\/www.trustedtranslations.com\/fr\/langues\">langues<\/a>. Ce sont des services extr\u00eamement importants.<\/p>\n<p>Image de Gerd Altmann chez Pixabay<\/p>\n","protected":false},"excerpt":{"rendered":"Les r\u00e9fugi\u00e9s se retrouvent dans une situation singuli\u00e8rement pr\u00e9caire, frustrante, effrayante. Ils ont \u00e9t\u00e9 d\u00e9plac\u00e9s de chez eux et sont oblig\u00e9s d\u2019essayer d\u2019\u00eatre admis \u00e0 entrer dans un pays \u00e9tranger\u2026.\n","protected":false},"author":116,"featured_media":217611,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[7517],"tags":[19224,19223,17681,19225,18269],"class_list":["post-218143","blog","type-blog","status-publish","format-standard","has-post-thumbnail","hentry","category-pour-acheteurs-de-traduction","tag-asile","tag-immigration-fr","tag-machine-vertaling","tag-refugies","tag-traduction-automatique-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les p\u00e9rils de la traduction IA dans les contextes de demande d\u2019asile - Trusted Translations, Inc.<\/title>\n<meta name=\"description\" content=\"La traduction automatique s\u2019est beaucoup am\u00e9lior\u00e9e au fil des ans\u00a0; cependant, dans des contextes d\u00e9licats tels que les demandes d\u2019asile, il est pr\u00e9f\u00e9rable de confier la traduction aux humains.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les p\u00e9rils de la traduction IA dans les contextes de demande d\u2019asile - Trusted Translations, Inc.\" \/>\n<meta property=\"og:description\" content=\"La traduction automatique s\u2019est beaucoup am\u00e9lior\u00e9e au fil des ans\u00a0; cependant, dans des contextes d\u00e9licats tels que les demandes d\u2019asile, il est pr\u00e9f\u00e9rable de confier la traduction aux humains.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile\" \/>\n<meta property=\"og:site_name\" content=\"Trusted Translations, Inc.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Trusted.Translations\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2023\/08\/refugees.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TrustedT9ns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile\"},\"author\":{\"name\":\"Aaron Damas\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#\\\/schema\\\/person\\\/fc971d06435454af57aa50cd18b75ee9\"},\"headline\":\"Les p\u00e9rils de la traduction IA dans les contextes de demande d\u2019asile\",\"datePublished\":\"2023-08-10T16:10:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile\"},\"wordCount\":1021,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/refugees.jpg\",\"keywords\":[\"asile\",\"immigration\",\"machine vertaling\",\"r\u00e9fugi\u00e9s\",\"traduction automatique\"],\"articleSection\":[\"Pour acheteurs de traduction\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile\",\"name\":\"Les p\u00e9rils de la traduction IA dans les contextes de demande d\u2019asile - Trusted Translations, Inc.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/refugees.jpg\",\"description\":\"La traduction automatique s\u2019est beaucoup am\u00e9lior\u00e9e au fil des ans\u00a0; cependant, dans des contextes d\u00e9licats tels que les demandes d\u2019asile, il est pr\u00e9f\u00e9rable de confier la traduction aux humains.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile#primaryimage\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/refugees.jpg\",\"contentUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/refugees.jpg\",\"width\":1280,\"height\":853,\"caption\":\"refugees\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pour acheteurs de traduction\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/blog\\\/category\\\/pour-acheteurs-de-traduction\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Les p\u00e9rils de la traduction IA dans les contextes de demande d\u2019asile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/\",\"name\":\"Trusted Translations, Inc.\",\"description\":\"Leader in translation and interpretation services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#organization\"},\"alternateName\":\"Trusted Translations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#organization\",\"name\":\"Trusted Translations\",\"alternateName\":\"Trusted Translations, Inc.\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"contentUrl\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"width\":500,\"height\":196,\"caption\":\"Trusted Translations\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Trusted.Translations\",\"https:\\\/\\\/x.com\\\/TrustedT9ns\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/trusted-translations\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/#\\\/schema\\\/person\\\/fc971d06435454af57aa50cd18b75ee9\",\"name\":\"Aaron Damas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99ffdc3b6a79c1aa2c73aa913680f39f771c8393d606465ea4d2d75c28b9c664?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99ffdc3b6a79c1aa2c73aa913680f39f771c8393d606465ea4d2d75c28b9c664?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99ffdc3b6a79c1aa2c73aa913680f39f771c8393d606465ea4d2d75c28b9c664?s=96&d=mm&r=g\",\"caption\":\"Aaron Damas\"},\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/fr\\\/author\\\/aarona\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les p\u00e9rils de la traduction IA dans les contextes de demande d\u2019asile - Trusted Translations, Inc.","description":"La traduction automatique s\u2019est beaucoup am\u00e9lior\u00e9e au fil des ans\u00a0; cependant, dans des contextes d\u00e9licats tels que les demandes d\u2019asile, il est pr\u00e9f\u00e9rable de confier la traduction aux humains.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile","og_locale":"fr_FR","og_type":"article","og_title":"Les p\u00e9rils de la traduction IA dans les contextes de demande d\u2019asile - Trusted Translations, Inc.","og_description":"La traduction automatique s\u2019est beaucoup am\u00e9lior\u00e9e au fil des ans\u00a0; cependant, dans des contextes d\u00e9licats tels que les demandes d\u2019asile, il est pr\u00e9f\u00e9rable de confier la traduction aux humains.","og_url":"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile","og_site_name":"Trusted Translations, Inc.","article_publisher":"https:\/\/www.facebook.com\/Trusted.Translations","og_image":[{"width":1280,"height":853,"url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2023\/08\/refugees.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TrustedT9ns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile#article","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile"},"author":{"name":"Aaron Damas","@id":"https:\/\/www.trustedtranslations.com\/fr\/#\/schema\/person\/fc971d06435454af57aa50cd18b75ee9"},"headline":"Les p\u00e9rils de la traduction IA dans les contextes de demande d\u2019asile","datePublished":"2023-08-10T16:10:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile"},"wordCount":1021,"publisher":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile#primaryimage"},"thumbnailUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2023\/08\/refugees.jpg","keywords":["asile","immigration","machine vertaling","r\u00e9fugi\u00e9s","traduction automatique"],"articleSection":["Pour acheteurs de traduction"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile","url":"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile","name":"Les p\u00e9rils de la traduction IA dans les contextes de demande d\u2019asile - Trusted Translations, Inc.","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile#primaryimage"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile#primaryimage"},"thumbnailUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2023\/08\/refugees.jpg","description":"La traduction automatique s\u2019est beaucoup am\u00e9lior\u00e9e au fil des ans\u00a0; cependant, dans des contextes d\u00e9licats tels que les demandes d\u2019asile, il est pr\u00e9f\u00e9rable de confier la traduction aux humains.","breadcrumb":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile#primaryimage","url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2023\/08\/refugees.jpg","contentUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2023\/08\/refugees.jpg","width":1280,"height":853,"caption":"refugees"},{"@type":"BreadcrumbList","@id":"https:\/\/www.trustedtranslations.com\/fr\/blog\/les-dangers-de-la-traduction-ai-dans-les-contextes-de-demande-d-asile#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.trustedtranslations.com\/fr"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.trustedtranslations.com\/fr\/blog"},{"@type":"ListItem","position":3,"name":"Pour acheteurs de traduction","item":"https:\/\/www.trustedtranslations.com\/fr\/blog\/category\/pour-acheteurs-de-traduction"},{"@type":"ListItem","position":4,"name":"Les p\u00e9rils de la traduction IA dans les contextes de demande d\u2019asile"}]},{"@type":"WebSite","@id":"https:\/\/www.trustedtranslations.com\/fr\/#website","url":"https:\/\/www.trustedtranslations.com\/fr\/","name":"Trusted Translations, Inc.","description":"Leader in translation and interpretation services.","publisher":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/#organization"},"alternateName":"Trusted Translations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trustedtranslations.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.trustedtranslations.com\/fr\/#organization","name":"Trusted Translations","alternateName":"Trusted Translations, Inc.","url":"https:\/\/www.trustedtranslations.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.trustedtranslations.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","contentUrl":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","width":500,"height":196,"caption":"Trusted Translations"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Trusted.Translations","https:\/\/x.com\/TrustedT9ns","https:\/\/www.linkedin.com\/company\/trusted-translations"]},{"@type":"Person","@id":"https:\/\/www.trustedtranslations.com\/fr\/#\/schema\/person\/fc971d06435454af57aa50cd18b75ee9","name":"Aaron Damas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/99ffdc3b6a79c1aa2c73aa913680f39f771c8393d606465ea4d2d75c28b9c664?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/99ffdc3b6a79c1aa2c73aa913680f39f771c8393d606465ea4d2d75c28b9c664?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99ffdc3b6a79c1aa2c73aa913680f39f771c8393d606465ea4d2d75c28b9c664?s=96&d=mm&r=g","caption":"Aaron Damas"},"url":"https:\/\/www.trustedtranslations.com\/fr\/author\/aarona"}]}},"toolset-meta":{"cpt-for-blogs":{"revisor":{"type":"textfield","raw":""},"revisor-image":{"type":"image","raw":"","attachment_id":null},"revisor-description":{"type":"textfield","raw":""},"revisor-link":{"type":"url","raw":""}}},"_links":{"self":[{"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/blog\/218143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/users\/116"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/comments?post=218143"}],"version-history":[{"count":0,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/blog\/218143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/media\/217611"}],"wp:attachment":[{"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/media?parent=218143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/categories?post=218143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/fr\/wp-json\/wp\/v2\/tags?post=218143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}