{"id":217439,"date":"2023-08-02T11:22:05","date_gmt":"2023-08-02T14:22:05","guid":{"rendered":"https:\/\/www.trustedtranslations.com\/?page_id=217439"},"modified":"2024-09-23T17:11:07","modified_gmt":"2024-09-23T20:11:07","slug":"indonesiano","status":"publish","type":"page","link":"https:\/\/www.trustedtranslations.com\/it\/lingua\/indonesiano","title":{"rendered":"Indonesiano"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":160117,"parent":123365,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-217439","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leader della traduzione in indonesiano: Trusted Translations<\/title>\n<meta name=\"description\" content=\"Trusted Translations: leader nei servizi di traduzione in indonesiano da parte di team di traduttori esperti in indonesiano. Richiedete un preventivo gratuito.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trustedtranslations.com\/it\/lingua\/indonesiano\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leader della traduzione in indonesiano: Trusted Translations\" \/>\n<meta property=\"og:description\" content=\"Trusted Translations: leader nei servizi di traduzione in indonesiano da parte di team di traduttori esperti in indonesiano. Richiedete un preventivo gratuito.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trustedtranslations.com\/it\/lingua\/indonesiano\" \/>\n<meta property=\"og:site_name\" content=\"Trusted Translations, Inc.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Trusted.Translations\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-23T20:11:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/08\/TT_NEW_FB-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TrustedT9ns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/lingua\\\/indonesiano\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/lingua\\\/indonesiano\",\"name\":\"Leader della traduzione in indonesiano: Trusted Translations\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/lingua\\\/indonesiano#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/lingua\\\/indonesiano#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/TT_NEW_FB-1.png\",\"description\":\"Trusted Translations: leader nei servizi di traduzione in indonesiano da parte di team di traduttori esperti in indonesiano. Richiedete un preventivo gratuito.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/lingua\\\/indonesiano#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/lingua\\\/indonesiano\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/lingua\\\/indonesiano#primaryimage\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/TT_NEW_FB-1.png\",\"contentUrl\":\"https:\\\/\\\/www.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/TT_NEW_FB-1.png\",\"caption\":\"TT NEW FB 1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/lingua\\\/indonesiano#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lingue\",\"item\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/lingua\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Indonesiano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/\",\"name\":\"Trusted Translations, Inc.\",\"description\":\"Leader in translation and interpretation services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/#organization\"},\"alternateName\":\"Trusted Translations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/#organization\",\"name\":\"Trusted Translations\",\"alternateName\":\"Trusted Translations, Inc.\",\"url\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"contentUrl\":\"https:\\\/\\\/static.trustedtranslations.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/TT_logo_WSIColors-2.png\",\"width\":500,\"height\":196,\"caption\":\"Trusted Translations\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trustedtranslations.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Trusted.Translations\",\"https:\\\/\\\/x.com\\\/TrustedT9ns\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/trusted-translations\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leader della traduzione in indonesiano: Trusted Translations","description":"Trusted Translations: leader nei servizi di traduzione in indonesiano da parte di team di traduttori esperti in indonesiano. Richiedete un preventivo gratuito.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trustedtranslations.com\/it\/lingua\/indonesiano","og_locale":"it_IT","og_type":"article","og_title":"Leader della traduzione in indonesiano: Trusted Translations","og_description":"Trusted Translations: leader nei servizi di traduzione in indonesiano da parte di team di traduttori esperti in indonesiano. Richiedete un preventivo gratuito.","og_url":"https:\/\/www.trustedtranslations.com\/it\/lingua\/indonesiano","og_site_name":"Trusted Translations, Inc.","article_publisher":"https:\/\/www.facebook.com\/Trusted.Translations","article_modified_time":"2024-09-23T20:11:07+00:00","og_image":[{"url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/08\/TT_NEW_FB-1.png","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TrustedT9ns","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.trustedtranslations.com\/it\/lingua\/indonesiano","url":"https:\/\/www.trustedtranslations.com\/it\/lingua\/indonesiano","name":"Leader della traduzione in indonesiano: Trusted Translations","isPartOf":{"@id":"https:\/\/www.trustedtranslations.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trustedtranslations.com\/it\/lingua\/indonesiano#primaryimage"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/it\/lingua\/indonesiano#primaryimage"},"thumbnailUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/08\/TT_NEW_FB-1.png","description":"Trusted Translations: leader nei servizi di traduzione in indonesiano da parte di team di traduttori esperti in indonesiano. Richiedete un preventivo gratuito.","breadcrumb":{"@id":"https:\/\/www.trustedtranslations.com\/it\/lingua\/indonesiano#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trustedtranslations.com\/it\/lingua\/indonesiano"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.trustedtranslations.com\/it\/lingua\/indonesiano#primaryimage","url":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/08\/TT_NEW_FB-1.png","contentUrl":"https:\/\/www.trustedtranslations.com\/wp-content\/uploads\/2022\/08\/TT_NEW_FB-1.png","caption":"TT NEW FB 1"},{"@type":"BreadcrumbList","@id":"https:\/\/www.trustedtranslations.com\/it\/lingua\/indonesiano#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trustedtranslations.com\/it"},{"@type":"ListItem","position":2,"name":"Lingue","item":"https:\/\/www.trustedtranslations.com\/it\/lingua"},{"@type":"ListItem","position":3,"name":"Indonesiano"}]},{"@type":"WebSite","@id":"https:\/\/www.trustedtranslations.com\/it\/#website","url":"https:\/\/www.trustedtranslations.com\/it\/","name":"Trusted Translations, Inc.","description":"Leader in translation and interpretation services.","publisher":{"@id":"https:\/\/www.trustedtranslations.com\/it\/#organization"},"alternateName":"Trusted Translations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trustedtranslations.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.trustedtranslations.com\/it\/#organization","name":"Trusted Translations","alternateName":"Trusted Translations, Inc.","url":"https:\/\/www.trustedtranslations.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.trustedtranslations.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","contentUrl":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2022\/01\/TT_logo_WSIColors-2.png","width":500,"height":196,"caption":"Trusted Translations"},"image":{"@id":"https:\/\/www.trustedtranslations.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Trusted.Translations","https:\/\/x.com\/TrustedT9ns","https:\/\/www.linkedin.com\/company\/trusted-translations"]}]}},"toolset-meta":{"dyk":{"mensaje-1":{"type":"textfield","raw":"Il giavanese \u00e8 la lingua madre di oltre 98 milioni di persone."},"mensaje-2":{"type":"textfield","raw":"Il Bahasa Indonesia appare sui media e nell\u2019istruzione formale, ma raramente nelle conversazioni."},"mensaje-3":{"type":"textfield","raw":"Il giavanese si concentra nell\u2019Indonesia centrale e orientale."},"mensaje-4":{"type":"textfield","raw":"L\u2019indonesiano appartiene alla stessa famiglia linguistica di tagalog, samoano e m\u0101ori."},"mensaje-5":{"type":"textfield","raw":""},"mensaje-6":{"type":"textfield","raw":""}},"single-page-template-fields":{"imgs-temp":{"type":"image","raw":["https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2023\/07\/Indonesia_port.jpg"],"repeatable":[{"raw":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2023\/07\/Indonesia_port.jpg"}]},"imgs-temp-cel":{"type":"image","raw":["https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2023\/07\/Indonesia.jpeg"],"repeatable":[{"raw":"https:\/\/static.trustedtranslations.com\/wp-content\/uploads\/2023\/07\/Indonesia.jpeg"}]},"img-temp-one-cel":{"type":"image","raw":"","attachment_id":null},"quotes":{"type":"textarea","raw":"<h1 style=\"margin-bottom: 12px;\">Servizi di traduzione in indonesiano<\/h1><em>Trusted Translations<\/em> \u00e8 un fornitore competitivo di servizi di traduzione in <strong>indonesiano<\/strong>. Per i progetti che richiedono traduzioni tra Bahasa Indonesia e inglese o altre lingue asiatiche ed europee, il nostro personale specializzato fornisce traduzioni accurate e sensibili dal punto di vista culturale. \r\n<div style=\"margin-top: 2.5vw;\"><a class=\"tt-btn-main-cta\" href=\"\/it\/quote\">RICHIEDI UN PREVENTIVO GRATUITO<\/a><\/div>"},"text-1":{"type":"textarea","raw":"<h2>Localizzazione in indonesiano da parte di esperti<\/h2>Biculturali anzich\u00e9 semplicemente bilingue, i nostri linguisti sono esperti nella localizzazione di traduzioni per target specifici in tempi ristretti. Si tratta di un talento particolarmente prezioso in un paese geograficamente frammentato come l\u2019Indonesia, un arcipelago che ospita oltre 300 gruppi etnici, molti dei quali parlano una lingua madre propria.\r\n<h2 style=\"margin-top: -10px;\">L\u2019indonesiano (Bahasa Indonesia) <\/h2>La lingua ufficiale dell\u2019Indonesia \u00e8 il Bahasa Indonesia, utilizzata a livello nazionale come lingua franca. Parlata da oltre 230 milioni di persone, questa lingua deriva da numerose fonti, tra cui il sanscrito, il malese, l\u2019<a href=\"https:\/\/www.trustedtranslations.com\/it\/lingua\/arabo\"><u>arabo<\/u><\/a> e l\u2019<a href=\"https:\/\/www.trustedtranslations.com\/it\/lingua\/olandese\"><u>olandese<\/u><\/a>. Seppur scritta in alfabeto latino, presenta diciotto consonanti e cinque vocali, con alcune modifiche che rappresentano i suoni che non corrispondono a suoni presenti nelle altre lingue. \r\n<h2> Varianti, dialetti e altre lingue in Indonesia<\/h2>\r\nTroppo eterogenea per essere classificata come un mercato unico, la popolazione indonesiana si ripartisce nel modo seguente: circa 40,2% di origine giavanese, 15,5% sundanese, 3,58% batak, 3,22% gruppi etnici sulawesi, 3,03% madurese e 2,88% betawi. Il restante 31,59% \u00e8 costituito da diversi gruppi etnici ancora pi\u00f9 ridotti.<br><br>\r\nCon la peculiare topografia (cinque isole principali e una trentina di arcipelaghi minori), non sorprende che gli indonesiani abbiano sviluppato una miriade di varianti linguistiche locali nel corso dei secoli. Tanto per fare un esempio, solo sull\u2019isola di Sulawesi (poco pi\u00f9 piccola della Gran Bretagna) si parlano ben 114 lingue indigene.\r\n<ul>\r\n    <li>Il <strong>giavanese<\/strong> \u00e8 parlato da circa 85 milioni di persone, gli Orang Jawa, che vivono principalmente sull\u2019isola di Giava e costituiscono il gruppo etnico pi\u00f9 numeroso dell\u2019Indonesia. Membro della famiglia linguistica austronesiana (maleo-polinesiana), la tonalit\u00e0 delle sue venti vocali e trentuno consonanti pu\u00f2 risultare scoraggiante alle orecchie occidentali.<\/li>\r\n    <li>Il <strong>sundanese<\/strong> viene parlato principalmente negli altopiani di Giava occidentale da circa 32 milioni di persone. Sebbene gli Orang Sunda siano musulmani devoti, alcuni concetti preislamici permeano ancora i loro rituali.<\/li>\r\n    <li>Il <strong>batak<\/strong> viene parlato dai circa sei milioni di discendenti di una popolazione proto-malese che vive in relativo isolamento negli altopiani intorno al lago Toba, nel nord di Sumatra. <\/li>\r\n<\/ul>"},"shortcode-map":{"type":"textfield","raw":""},"dyk-shortcode":{"type":"textfield","raw":"[elementor-template id=\"146751\"]"},"text-2":{"type":"textarea","raw":"<h2>Panoramica economica<\/h2>Con un PIL che raggiunger\u00e0 i 9,1 trilioni di dollari e un\u2019economia al quarto posto a livello mondiale entro il 2045, l\u2019Indonesia \u00e8 il pi\u00f9 grande mercato emergente del sud-est asiatico. Con una crescita generale di oltre il 5% l\u2019anno, si prevede che il suo giro d\u2019affari su internet raggiunger\u00e0 presto i 130 miliardi di dollari. <br><br>\r\nPaese a reddito medio, questo membro del G20 di recente industrializzazione \u00e8 un importante esportatore di petrolio greggio e gas naturale, bilanciato dalle importazioni di <a href=\"https:\/\/www.trustedtranslations.com\/it\/industrie\/produzione\"><u>prodotti petroliferi raffinati e medicinali<\/u><\/a>. Le esportazioni totali potrebbero superare i 300 miliardi di dollari entro il 2024, in particolare grazie ad altre materie prime come rame, bauxite e stagno; l\u2019Indonesia \u00e8 anche un importante fornitore di gomma, caff\u00e8, cacao e olio di palma.\r\n<h2>Fare affari in Indonesia<\/h2>\r\nIndirizzandosi verso un\u2019economia pi\u00f9 moderna basata sull\u2019industria e orientata ai servizi, i piani e le politiche del governo si sono concentrati sulla creazione di nuove infrastrutture, guidando al contempo una crescita sostenibile attraverso un sistema fiscale favorevole alle imprese. Le citt\u00e0 pi\u00f9 grandi si stanno trasformando in centri specializzati per l\u2019<a href=\"https:\/\/www.trustedtranslations.com\/it\/industrie\/software\"><u>elettronica<\/u><\/a>, <a href=\"https:\/\/www.trustedtranslations.com\/it\/industrie\/manuale\"><u>i macchinari<\/u><\/a> e il settore automobilistico, con grande attenzione al settore dell\u2019ospitalit\u00e0 e del turismo, stimolato dalla presenza di diversi siti dichiarati patrimonio mondiale dall\u2019UNESCO.<br><br>\r\nNonostante tutti questi vantaggi, l\u2019ambiente imprenditoriale dell\u2019Indonesia non \u00e8 facile da affrontare se non si ha familiarit\u00e0 con la cultura locale, le complesse normative e i requisiti specifici del settore. Per questo i servizi di traduzione biculturale, come quelli offerti da <em>Trusted Translations<\/em>, costituiscono una vera e propria miniera d\u2019oro, tagliando i costi e consentendo di risparmiare tempo nella comprensione di questioni complesse come autorizzazioni e licenze. Gli specialisti di Trusted Translations sono di grande aiuto anche nello sviluppo delle reti personali, fondamentali per svolgere attivit\u00e0 commerciali in Indonesia."},"state":{"type":"textfield","raw":""},"city":{"type":"textarea","raw":[]}}},"_links":{"self":[{"href":"https:\/\/www.trustedtranslations.com\/it\/wp-json\/wp\/v2\/pages\/217439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trustedtranslations.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.trustedtranslations.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/it\/wp-json\/wp\/v2\/comments?post=217439"}],"version-history":[{"count":0,"href":"https:\/\/www.trustedtranslations.com\/it\/wp-json\/wp\/v2\/pages\/217439\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/it\/wp-json\/wp\/v2\/pages\/123365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trustedtranslations.com\/it\/wp-json\/wp\/v2\/media\/160117"}],"wp:attachment":[{"href":"https:\/\/www.trustedtranslations.com\/it\/wp-json\/wp\/v2\/media?parent=217439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}